{"id":35294,"date":"2026-04-05T01:00:00","date_gmt":"2026-04-04T23:00:00","guid":{"rendered":"https:\/\/vedruna.org\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/"},"modified":"2026-05-05T10:22:33","modified_gmt":"2026-05-05T08:22:33","slug":"pasqua-desperanca-compartim-la-carta-final-del-cga-2026","status":"publish","type":"post","link":"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/","title":{"rendered":"Pasqua d&#8217;esperan\u00e7a: compartim la carta final del CGA 2026"},"content":{"rendered":"\n<p>En aquesta Pasqua, <strong>temps de Vida nova i d&#8217;esperan\u00e7a renovada<\/strong> , volem unir-nos a l&#8217;alegria del Ressuscitat que segueix fent-se present al nostre caminar com a Fam\u00edlia Vedruna. Des d&#8217;aquesta certesa que ens sost\u00e9 i ens impulsa, compartim la salutaci\u00f3 pasqual de l&#8217;Equip General, convidant-nos a acollir aquest temps com a gr\u00e0cia i horitz\u00f3 de futur: <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;Conreem la flor de l&#8217;Esperan\u00e7a entre les nafres del Ressuscitat.&#8221; &#8211; Pedro Casald\u00e0liga<\/p>\n\n\n\n<p><strong>Mentre seguim cultivant l&#8217;Esperan\u00e7a com a poble en cam\u00ed, rebeu la nostra salutaci\u00f3 de Feli\u00e7 Pasqua de Resurrecci\u00f3.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right\">Germanes de l&#8217;equip general<\/p>\n<\/blockquote>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<p>En aquesta mateixa clau d&#8217;esperan\u00e7a i de vida que reneix, posem a disposici\u00f3 de tota la Fam\u00edlia Vedruna la <strong>carta final del Consell General Ampliat (CGA) 2026<\/strong> , celebrat a Vic del 9 al 23 de mar\u00e7, en el marc del Bicentenari de la Congregaci\u00f3.<\/p>\n\n<p>Han estat dies intensos de trobada, escolta, discerniment i oraci\u00f3, en qu\u00e8 l&#8217;Equip General, els Equips Provincials i de Delegaci\u00f3, juntament amb les diferents comissions internacionals, hem aprofundit en el cam\u00ed recorregut des del XXVIII Cap\u00edtol General i en els desafiaments que s&#8217;obren per als propers anys.<\/p>\n\n<p>La carta que avui posem a disposici\u00f3 recull les resson\u00e0ncies m\u00e9s significatives d&#8217;aquest proc\u00e9s, els signes de vida nova descoberts al mig de les podes, i les l\u00ednies que orientaran el nostre caminar com a Congregaci\u00f3 i Fam\u00edlia Carism\u00e0tica fins al proper Cap\u00edtol General.<\/p>\n\n<p>Aquest document neix des de l&#8217;experi\u00e8ncia viscuda al CGA: una experi\u00e8ncia profundament marcada per la sinodalitat, esperan\u00e7a i fidelitat creativa al carisma de Santa Joaquima de Vedruna. Des de Vic, lloc dels nostres or\u00edgens, tornem a escoltar la crida a \u201cn\u00e9ixer de nou\u201d, acollint amb confian\u00e7a l&#8217;acci\u00f3 de la Ruah que segueix suscitant vida en all\u00f2 petit i quotidi\u00e0. <\/p>\n\n<p>La carta mira especialment al proper trienni i ens convida a continuar creixent a:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>La vida intercultural i sinodal<\/li>\n\n\n\n<li>La cura integral de les persones i de la creaci\u00f3<\/li>\n\n\n\n<li>La missi\u00f3 compartida com a Fam\u00edlia Carism\u00e0tica<\/li>\n\n\n\n<li>La cultura vocacional i el caminar amb joves<\/li>\n\n\n\n<li>La reorganitzaci\u00f3 d&#8217;estructures al servei de la missi\u00f3<\/li>\n<\/ul>\n\n<p>Amb alegria pasqual, us convidem a llegir-la, pregar-la i compartir-la en comunitats, projectes i espais de missi\u00f3.<\/p>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/drive.google.com\/file\/d\/1r5y-5A9kFuZ3arfQsf3VUKo-ueF0DivJ\/view?usp=sharing\">Descarregar ac\u00ed carta final del CGA 2026<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/drive.google.com\/file\/d\/1MeMhu5zVR76WxN3CdfEkShCTHi-mD1T2\/view?usp=drive_link\">Descarregar ici la lettre finale du CGE 2026<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/drive.google.com\/file\/d\/1RYZkUjXZPrhfDYx7rCqzAJIRoVhLFiGb\/view?usp=sharing\">Download the final letter from the EGC 2026 here<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/drive.google.com\/file\/d\/13ZFSr42canpVFV2pBVxSTi0i5ICndriF\/view?usp=drive_link\">Descarregueu aqu\u00ed la carta final del CGA 2026<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/drive.google.com\/file\/d\/1FbpfCkKZgXIe9ITGl239mAD2Bky2Jx4u\/view?usp=drive_link\">CGA 2026\uc758 \ucd5c\uc885 \uc11c\uac04\uc740 \uc774\ucabd\uc73c\ub85c\ubd80\ud130 \ub2e4\uc6b4\ub85c\ub4dc<\/a><\/div>\n<\/div>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p><strong>Que la Pasqua del Senyor renovi la nostra esperan\u00e7a i ens impulsi a seguir teixint vida, just\u00edcia i caritat all\u00e0 on som<\/strong> .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En aquesta Pasqua, temps de Vida nova i d&#8217;esperan\u00e7a renovada , volem unir-nos a l&#8217;alegria del Ressuscitat que segueix fent-se present al nostre caminar com a Fam\u00edlia Vedruna. Des d&#8217;aquesta certesa que ens sost\u00e9 i ens impulsa, compartim la salutaci\u00f3 pasqual de l&#8217;Equip General, convidant-nos a acollir aquest temps com a gr\u00e0cia i horitz\u00f3 de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":35295,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[560],"tags":[],"class_list":["post-35294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cga-consell-general-ampliat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pasqua d&#039;esperan\u00e7a: compartim la carta final del CGA 2026 - Carmelitas de la Caridad Vedruna<\/title>\n<meta name=\"description\" content=\"Celebrant la Pasqua, posem a disposici\u00f3 de tota la Fam\u00edlia Vedruna la carta final del Consell General Ampliat (CGA) 2026, celebrat a Vic del 9 al 23 de mar\u00e7, en el marc del Bicentenari de la Congregaci\u00f3.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pasqua d&#039;esperan\u00e7a: compartim la carta final del CGA 2026 - Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"og:description\" content=\"Celebrant la Pasqua, posem a disposici\u00f3 de tota la Fam\u00edlia Vedruna la carta final del Consell General Ampliat (CGA) 2026, celebrat a Vic del 9 al 23 de mar\u00e7, en el marc del Bicentenari de la Congregaci\u00f3.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-04T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T08:22:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vedruna.org\/wp-content\/uploads\/2026\/04\/Banner-webok-1024x468.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"468\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Oriana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oriana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\\\/\"},\"author\":{\"name\":\"Oriana\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/#\\\/schema\\\/person\\\/3ead809e9735eaa7b26dd6ad5f18e716\"},\"headline\":\"Pasqua d&#8217;esperan\u00e7a: compartim la carta final del CGA 2026\",\"datePublished\":\"2026-04-04T23:00:00+00:00\",\"dateModified\":\"2026-05-05T08:22:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\\\/\"},\"wordCount\":451,\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Banner-webok.png\",\"articleSection\":[\"CGA - Consell General Ampliat\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\\\/\",\"name\":\"Pasqua d'esperan\u00e7a: compartim la carta final del CGA 2026 - Carmelitas de la Caridad Vedruna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Banner-webok.png\",\"datePublished\":\"2026-04-04T23:00:00+00:00\",\"dateModified\":\"2026-05-05T08:22:33+00:00\",\"description\":\"Celebrant la Pasqua, posem a disposici\u00f3 de tota la Fam\u00edlia Vedruna la carta final del Consell General Ampliat (CGA) 2026, celebrat a Vic del 9 al 23 de mar\u00e7, en el marc del Bicentenari de la Congregaci\u00f3.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vedruna.org\\\/ca\\\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Banner-webok.png\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Banner-webok.png\",\"width\":2080,\"height\":950},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pasqua d&#8217;esperan\u00e7a: compartim la carta final del CGA 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/\",\"name\":\"Carmelitas de la Caridad Vedruna\",\"description\":\"Carmelitas de la caridad\",\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/#organization\",\"name\":\"Carmelitas de la caridad Vedruna\",\"url\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"width\":1200,\"height\":463,\"caption\":\"Carmelitas de la caridad Vedruna\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/#\\\/schema\\\/person\\\/3ead809e9735eaa7b26dd6ad5f18e716\",\"name\":\"Oriana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g\",\"caption\":\"Oriana\"},\"url\":\"https:\\\/\\\/vedruna.org\\\/ca\\\/author\\\/oriana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pasqua d'esperan\u00e7a: compartim la carta final del CGA 2026 - Carmelitas de la Caridad Vedruna","description":"Celebrant la Pasqua, posem a disposici\u00f3 de tota la Fam\u00edlia Vedruna la carta final del Consell General Ampliat (CGA) 2026, celebrat a Vic del 9 al 23 de mar\u00e7, en el marc del Bicentenari de la Congregaci\u00f3.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/","og_locale":"ca_ES","og_type":"article","og_title":"Pasqua d'esperan\u00e7a: compartim la carta final del CGA 2026 - Carmelitas de la Caridad Vedruna","og_description":"Celebrant la Pasqua, posem a disposici\u00f3 de tota la Fam\u00edlia Vedruna la carta final del Consell General Ampliat (CGA) 2026, celebrat a Vic del 9 al 23 de mar\u00e7, en el marc del Bicentenari de la Congregaci\u00f3.","og_url":"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/","og_site_name":"Carmelitas de la Caridad Vedruna","article_published_time":"2026-04-04T23:00:00+00:00","article_modified_time":"2026-05-05T08:22:33+00:00","og_image":[{"width":1024,"height":468,"url":"https:\/\/vedruna.org\/wp-content\/uploads\/2026\/04\/Banner-webok-1024x468.png","type":"image\/png"}],"author":"Oriana","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Oriana","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/#article","isPartOf":{"@id":"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/"},"author":{"name":"Oriana","@id":"https:\/\/vedruna.org\/ca\/#\/schema\/person\/3ead809e9735eaa7b26dd6ad5f18e716"},"headline":"Pasqua d&#8217;esperan\u00e7a: compartim la carta final del CGA 2026","datePublished":"2026-04-04T23:00:00+00:00","dateModified":"2026-05-05T08:22:33+00:00","mainEntityOfPage":{"@id":"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/"},"wordCount":451,"publisher":{"@id":"https:\/\/vedruna.org\/ca\/#organization"},"image":{"@id":"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2026\/04\/Banner-webok.png","articleSection":["CGA - Consell General Ampliat"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/","url":"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/","name":"Pasqua d'esperan\u00e7a: compartim la carta final del CGA 2026 - Carmelitas de la Caridad Vedruna","isPartOf":{"@id":"https:\/\/vedruna.org\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/#primaryimage"},"image":{"@id":"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2026\/04\/Banner-webok.png","datePublished":"2026-04-04T23:00:00+00:00","dateModified":"2026-05-05T08:22:33+00:00","description":"Celebrant la Pasqua, posem a disposici\u00f3 de tota la Fam\u00edlia Vedruna la carta final del Consell General Ampliat (CGA) 2026, celebrat a Vic del 9 al 23 de mar\u00e7, en el marc del Bicentenari de la Congregaci\u00f3.","breadcrumb":{"@id":"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/#primaryimage","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2026\/04\/Banner-webok.png","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2026\/04\/Banner-webok.png","width":2080,"height":950},{"@type":"BreadcrumbList","@id":"https:\/\/vedruna.org\/ca\/pasqua-desperanca-compartim-la-carta-final-del-cga-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vedruna.org\/ca\/"},{"@type":"ListItem","position":2,"name":"Pasqua d&#8217;esperan\u00e7a: compartim la carta final del CGA 2026"}]},{"@type":"WebSite","@id":"https:\/\/vedruna.org\/ca\/#website","url":"https:\/\/vedruna.org\/ca\/","name":"Carmelitas de la Caridad Vedruna","description":"Carmelitas de la caridad","publisher":{"@id":"https:\/\/vedruna.org\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vedruna.org\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/vedruna.org\/ca\/#organization","name":"Carmelitas de la caridad Vedruna","url":"https:\/\/vedruna.org\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/vedruna.org\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","width":1200,"height":463,"caption":"Carmelitas de la caridad Vedruna"},"image":{"@id":"https:\/\/vedruna.org\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/vedruna.org\/ca\/#\/schema\/person\/3ead809e9735eaa7b26dd6ad5f18e716","name":"Oriana","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g","caption":"Oriana"},"url":"https:\/\/vedruna.org\/ca\/author\/oriana\/"}]}},"_links":{"self":[{"href":"https:\/\/vedruna.org\/ca\/wp-json\/wp\/v2\/posts\/35294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vedruna.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vedruna.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vedruna.org\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vedruna.org\/ca\/wp-json\/wp\/v2\/comments?post=35294"}],"version-history":[{"count":7,"href":"https:\/\/vedruna.org\/ca\/wp-json\/wp\/v2\/posts\/35294\/revisions"}],"predecessor-version":[{"id":35759,"href":"https:\/\/vedruna.org\/ca\/wp-json\/wp\/v2\/posts\/35294\/revisions\/35759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vedruna.org\/ca\/wp-json\/wp\/v2\/media\/35295"}],"wp:attachment":[{"href":"https:\/\/vedruna.org\/ca\/wp-json\/wp\/v2\/media?parent=35294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vedruna.org\/ca\/wp-json\/wp\/v2\/categories?post=35294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vedruna.org\/ca\/wp-json\/wp\/v2\/tags?post=35294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}