{"id":4387,"date":"2023-07-28T09:23:04","date_gmt":"2023-07-28T07:23:04","guid":{"rendered":"https:\/\/vedruna.org\/?post_type=cronicas&#038;p=4387"},"modified":"2023-07-29T17:25:38","modified_gmt":"2023-07-29T15:25:38","slug":"cronica-23-de-julio-de-2023","status":"publish","type":"cronicas","link":"https:\/\/vedruna.org\/fr\/cronicas\/cronica-23-de-julio-de-2023\/","title":{"rendered":"23 de Julio de 2023"},"content":{"rendered":"\n<p><strong>Revisi\u00f3n de la Estructuras<\/strong><\/p>\n\n\n\n<p>El domingo 23 de Julio, empezamos con una Eucarist\u00eda en la que compartimos la Palabra, por parejas, en lugar de la homil\u00eda del celebrante. Acabamos la Celebraci\u00f3n con una danza en la que bendecimos la tierra, a las presentes, a nuestras antepasadas y a nosotras mismas.&nbsp;<\/p>\n\n\n\n<p>La tecnolog\u00eda nos facilit\u00f3 conectar con Camer\u00fan donde se encontraba Bego\u00f1a Mart\u00ednez, Laica de la asociaci\u00f3n Adsis,&nbsp; asesora de la Comisi\u00f3n de Revisi\u00f3n de Estructuras. Las otras miembros de la comisi\u00f3n \u2013 Noeli Massoni, Montserrat Fenosa, y Maggie D\u2019Costa, nos encontr\u00e1bamos en la sala capitular, dispuestas a compartir el trabajo de la comisi\u00f3n con todas las capitulares.<\/p>\n\n\n\n<p>Despu\u00e9s Mar\u00eda In\u00e9s present\u00f3 a Bego\u00f1a, que introdujo el tema bas\u00e1ndose en los resultados de la encuesta de revisi\u00f3n de estructuras, realizada por las hermanas. Su presentaci\u00f3n fue intercalada con una din\u00e1mica en la sala, invitando a expresar qu\u00e9 estructuras nos parece que sostienen nuestra vida y misi\u00f3n. Acabada la din\u00e1mica, Bego\u00f1a sigui\u00f3 exponiendo los 4 focos derivados de las encuestas: 1. Comunicaci\u00f3n interna; 2. Pertenencia y Corresponsabilidad; 3. Nuevo estilo de liderazgo; 4.Equidad versus Igualdad.<\/p>\n\n\n\n<p>Despu\u00e9s, tuvimos un tiempo para la reflexi\u00f3n personal y luego contestar si cada uno de los focos es adecuado o no, y dar raz\u00f3n de ello. Compartimos en grupos lo reflexionado y consensuamos las recomendaciones y acciones que ve\u00edamos para cada foco.&nbsp;<\/p>\n\n\n\n<p>Por la tarde, cada una se apunt\u00f3 para profundizar en uno de los focos, de modo que cada grupo se centr\u00f3 en elegir recomendaciones y acciones para ese foco,&nbsp;<\/p>\n\n\n\n<p>teniendo como base las aportaciones de todos los grupos de la ma\u00f1ana respecto al mismo.<\/p>\n\n\n\n<p>La reflexi\u00f3n de cada grupo se escribi\u00f3 en papel\u00f3grafos, que colgamos a lo largo del pasillo. Luego, cada una, en silencio, paseamos leyendo todas las aportaciones y posteriormente tuvimos que se\u00f1alar dos recomendaciones, y dos acciones que cre\u00edamos m\u00e1s prioritarias para cada foco. As\u00ed tuvimos una apreciaci\u00f3n global para saber cuales son las tendencias.&nbsp;<\/p>\n\n\n\n<p>Acabamos el d\u00eda con una breve oraci\u00f3n, escuchando I Cor. 12, mientras algunas sosten\u00edan los papeles con las estructuras citadas en la din\u00e1mica de la ma\u00f1ana. Con el canto del Cap\u00edtulo, expresamos nuestro deseo de \u201cNacer de Nuevo\u201d, cant\u00e1ndolo en distintos idiomas.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-right\"><strong>Informa: Maggie D\u2019Costa, Provincia de India<\/strong><\/p>\n\n\n\n<p>Descargar cr\u00f3nica AQU\u00cd<\/p>\n","protected":false},"featured_media":4388,"template":"","class_list":["post-4387","cronicas","type-cronicas","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cap\u00edtulo 28 | Cr\u00f3nica: Revisi\u00f3n de la Estructuras<\/title>\n<meta name=\"description\" content=\"La tecnolog\u00eda nos facilit\u00f3 conectar con Camer\u00fan donde se encontraba Bego\u00f1a Mart\u00ednez, Laica de la asociaci\u00f3n Adsis,\u00a0 asesora de la Comisi\u00f3n de Revisi\u00f3n de Estructuras. Las otras miembros de la comisi\u00f3n \u2013 Noeli Massoni, Montserrat Fenosa, y Maggie D\u2019Costa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vedruna.org\/fr\/cronicas\/cronica-23-de-julio-de-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cap\u00edtulo 28 | Cr\u00f3nica: Revisi\u00f3n de la Estructuras\" \/>\n<meta property=\"og:description\" content=\"La tecnolog\u00eda nos facilit\u00f3 conectar con Camer\u00fan donde se encontraba Bego\u00f1a Mart\u00ednez, Laica de la asociaci\u00f3n Adsis,\u00a0 asesora de la Comisi\u00f3n de Revisi\u00f3n de Estructuras. Las otras miembros de la comisi\u00f3n \u2013 Noeli Massoni, Montserrat Fenosa, y Maggie D\u2019Costa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vedruna.org\/fr\/cronicas\/cronica-23-de-julio-de-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-29T15:25:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/07\/DSC_0020-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1745\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cronicas\\\/cronica-23-de-julio-de-2023\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cronicas\\\/cronica-23-de-julio-de-2023\\\/\",\"name\":\"Cap\u00edtulo 28 | Cr\u00f3nica: Revisi\u00f3n de la Estructuras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cronicas\\\/cronica-23-de-julio-de-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cronicas\\\/cronica-23-de-julio-de-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/DSC_0020-scaled.jpg\",\"datePublished\":\"2023-07-28T07:23:04+00:00\",\"dateModified\":\"2023-07-29T15:25:38+00:00\",\"description\":\"La tecnolog\u00eda nos facilit\u00f3 conectar con Camer\u00fan donde se encontraba Bego\u00f1a Mart\u00ednez, Laica de la asociaci\u00f3n Adsis,\u00a0 asesora de la Comisi\u00f3n de Revisi\u00f3n de Estructuras. Las otras miembros de la comisi\u00f3n \u2013 Noeli Massoni, Montserrat Fenosa, y Maggie D\u2019Costa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cronicas\\\/cronica-23-de-julio-de-2023\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vedruna.org\\\/fr\\\/cronicas\\\/cronica-23-de-julio-de-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cronicas\\\/cronica-23-de-julio-de-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/DSC_0020-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/DSC_0020-scaled.jpg\",\"width\":2560,\"height\":1745},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cronicas\\\/cronica-23-de-julio-de-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cr\u00f3nicas\",\"item\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cronicas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"23 de Julio de 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"name\":\"Carmelitas de la Caridad Vedruna\",\"description\":\"Carmelitas de la caridad\",\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\",\"name\":\"Carmelitas de la caridad Vedruna\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"width\":1200,\"height\":463,\"caption\":\"Carmelitas de la caridad Vedruna\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cap\u00edtulo 28 | Cr\u00f3nica: Revisi\u00f3n de la Estructuras","description":"La tecnolog\u00eda nos facilit\u00f3 conectar con Camer\u00fan donde se encontraba Bego\u00f1a Mart\u00ednez, Laica de la asociaci\u00f3n Adsis,\u00a0 asesora de la Comisi\u00f3n de Revisi\u00f3n de Estructuras. Las otras miembros de la comisi\u00f3n \u2013 Noeli Massoni, Montserrat Fenosa, y Maggie D\u2019Costa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vedruna.org\/fr\/cronicas\/cronica-23-de-julio-de-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Cap\u00edtulo 28 | Cr\u00f3nica: Revisi\u00f3n de la Estructuras","og_description":"La tecnolog\u00eda nos facilit\u00f3 conectar con Camer\u00fan donde se encontraba Bego\u00f1a Mart\u00ednez, Laica de la asociaci\u00f3n Adsis,\u00a0 asesora de la Comisi\u00f3n de Revisi\u00f3n de Estructuras. Las otras miembros de la comisi\u00f3n \u2013 Noeli Massoni, Montserrat Fenosa, y Maggie D\u2019Costa.","og_url":"https:\/\/vedruna.org\/fr\/cronicas\/cronica-23-de-julio-de-2023\/","og_site_name":"Carmelitas de la Caridad Vedruna","article_modified_time":"2023-07-29T15:25:38+00:00","og_image":[{"width":2560,"height":1745,"url":"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/07\/DSC_0020-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vedruna.org\/fr\/cronicas\/cronica-23-de-julio-de-2023\/","url":"https:\/\/vedruna.org\/fr\/cronicas\/cronica-23-de-julio-de-2023\/","name":"Cap\u00edtulo 28 | Cr\u00f3nica: Revisi\u00f3n de la Estructuras","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vedruna.org\/fr\/cronicas\/cronica-23-de-julio-de-2023\/#primaryimage"},"image":{"@id":"https:\/\/vedruna.org\/fr\/cronicas\/cronica-23-de-julio-de-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/07\/DSC_0020-scaled.jpg","datePublished":"2023-07-28T07:23:04+00:00","dateModified":"2023-07-29T15:25:38+00:00","description":"La tecnolog\u00eda nos facilit\u00f3 conectar con Camer\u00fan donde se encontraba Bego\u00f1a Mart\u00ednez, Laica de la asociaci\u00f3n Adsis,\u00a0 asesora de la Comisi\u00f3n de Revisi\u00f3n de Estructuras. Las otras miembros de la comisi\u00f3n \u2013 Noeli Massoni, Montserrat Fenosa, y Maggie D\u2019Costa.","breadcrumb":{"@id":"https:\/\/vedruna.org\/fr\/cronicas\/cronica-23-de-julio-de-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vedruna.org\/fr\/cronicas\/cronica-23-de-julio-de-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/cronicas\/cronica-23-de-julio-de-2023\/#primaryimage","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/07\/DSC_0020-scaled.jpg","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/07\/DSC_0020-scaled.jpg","width":2560,"height":1745},{"@type":"BreadcrumbList","@id":"https:\/\/vedruna.org\/fr\/cronicas\/cronica-23-de-julio-de-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vedruna.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Cr\u00f3nicas","item":"https:\/\/vedruna.org\/fr\/cronicas\/"},{"@type":"ListItem","position":3,"name":"23 de Julio de 2023"}]},{"@type":"WebSite","@id":"https:\/\/vedruna.org\/fr\/#website","url":"https:\/\/vedruna.org\/fr\/","name":"Carmelitas de la Caridad Vedruna","description":"Carmelitas de la caridad","publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vedruna.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vedruna.org\/fr\/#organization","name":"Carmelitas de la caridad Vedruna","url":"https:\/\/vedruna.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","width":1200,"height":463,"caption":"Carmelitas de la caridad Vedruna"},"image":{"@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/cronicas\/4387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/cronicas"}],"about":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/types\/cronicas"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media\/4388"}],"wp:attachment":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media?parent=4387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}