{"id":10750,"date":"2024-05-20T10:11:25","date_gmt":"2024-05-20T08:11:25","guid":{"rendered":"https:\/\/vedruna.org\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/"},"modified":"2024-05-23T23:18:57","modified_gmt":"2024-05-23T21:18:57","slug":"lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024","status":"publish","type":"post","link":"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/","title":{"rendered":"Lettre \u00e0 la famille Vedruna \u00e0 l&rsquo;occasion de la f\u00eate du 22 mai 2024"},"content":{"rendered":"\n<p>Ch\u00e8re famille, famille, oui, nous sommes une famille, parce que chacun d&rsquo;entre nous, \u00e0 partir de nos diff\u00e9rents r\u00f4les et services, dans le m\u00eame c\u0153ur, vit et partage son exp\u00e9rience et ses appels au Bon J\u00e9sus.<\/p>\n\n<p>Cela fait quelques jours que je ne vous ai pas \u00e9crit, mais j&rsquo;ai l&rsquo;occasion de le faire \u00e0 l&rsquo;occasion de la f\u00eate de la Trinit\u00e9, le 26 mai. Mais en fait, la raison de ma lettre est que le 22 de ce mois, vous avez tenu \u00e0 rappeler le jour o\u00f9 l&rsquo;\u00c9glise dit que c&rsquo;est ma f\u00eate. Je dirais que c&rsquo;est le jour du souvenir, de mon engagement envers l&rsquo;\u00c9vangile, n\u00e9 de mon bapt\u00eame, d&rsquo;\u00eatre la Bonne Nouvelle partout o\u00f9 je me trouve.  <\/p>\n\n<p>\u00c0 propos, j&rsquo;aime \u00e0 rappeler qu&rsquo;il n&rsquo;y a pas encore un an que, dans ma maison de Vic, qui est votre maison, nous, la Famille, nous sommes r\u00e9unis pour examiner ce que nous faisons et comment nous vivons notre engagement \u00e0 travailler pour la gloire de Dieu et le bien de notre prochain. Ce fut une grande joie pour moi qu&rsquo;apr\u00e8s avoir \u00e9cout\u00e9 l&rsquo;Esprit, ils d\u00e9couvrent qu&rsquo;il s&rsquo;agit de <em>na\u00eetre \u00e0 nouveau<\/em>. Na\u00eetre de nouveau est un grand mot, car il s&rsquo;agit de na\u00eetre de l&rsquo;eau et de l&rsquo;Esprit.  <\/p>\n\n<p>Peut-\u00eatre que si nous le rendons plus simple, ou plus pratique, il sera plus facile \u00e0 comprendre ; prenons quelques exemples : dans les communaut\u00e9s, vivre avec conscience et intensit\u00e9 l&rsquo;art de la rencontre, en pensant toujours que le b\u00e9n\u00e9ficiaire est la mission.<\/p>\n\n<p>Dans les t\u00e2ches de la mission, en aiguisant nos yeux et nos c\u0153urs pour saisir les personnes, les espaces et les r\u00e9alit\u00e9s qui nous demandent une plus grande proximit\u00e9, qui nous crient l&rsquo;urgence de l&rsquo;humanisation, de venir tisser le nous.<\/p>\n\n<p>Dans les familles, en renfor\u00e7ant l&rsquo;amour, \u00e0 la maison, avec les coll\u00e8gues et les voisins.<\/p>\n\n<p>Dans notre environnement, avec notre m\u00e8re la Terre, en regardant les d\u00e9chets que nous produisons et en nous demandant si nous avons besoin de tout cela. Que se passe-t-il si je me passe de&#8230; ? Et dans un sens plus large, de s&rsquo;impliquer dans des groupes et des mouvements qui luttent pour une \u00e9cologie int\u00e9grale et qui prennent soin de notre maison commune !  <\/p>\n\n<p>Ch\u00e8re famille, je vous encourage \u00e0 \u00eatre attentifs \u00e0 ce qui se passe, dans vos milieux, nous vivons une \u00e9poque de nombreux d\u00e9fis, comme la culture de la synodalit\u00e9. Le dernier document du chapitre se lit comme suit : \u00ab\u00a0<em>La synodalit\u00e9, c&rsquo;est marcher, prier, r\u00eaver et participer ensemble. C&rsquo;est un chemin de discernement en commun, \u00e0 l&rsquo;\u00e9coute de l&rsquo;Esprit. C&rsquo;est un appel \u00e0 la conversion personnelle, communautaire et eccl\u00e9siale visant \u00e0 construire un monde plus juste et plus \u00e9galitaire, en b\u00e2tissant une communaut\u00e9 eccl\u00e9siale fraternelle, sororale et missionnaire au service du bien commun\u00a0\u00bb.  <\/em><\/p>\n\n<p>Je vous encourage \u00e0 ouvrir vos yeux et vos oreilles pour savoir quoi et comment r\u00e9agir \u00e0 tout ce qui se passe, car  <em>\u00ab\u00a0J\u00e9sus lui-m\u00eame montre par sa vie comment la relation avec le P\u00e8re, dans l&rsquo;Esprit, traverse chaque d\u00e9cision quotidienne ou chaque carrefour sur la route qu&rsquo;il parcourt\u00a0\u00bb.<\/em> <\/p>\n\n<p><em>\u00ab\u00a0<\/em><em>Soyez tr\u00e8s confiant : tout se passera bien, m\u00eame mieux que vous ne le pensez. Si nous nous effor\u00e7ons de faire le bien, le Seigneur nous donnera sa lumi\u00e8re pour faire le bien et les moyens de le faire.<\/em><em>\u00ab\u00a0<\/em><\/p>\n\n<p class=\"has-text-align-right\">Je vous embrasse fraternellement et fraternellement.<\/p>\n\n<figure class=\"wp-block-image alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"405\" height=\"149\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/Firma.jpg\" alt=\"\" class=\"wp-image-2312\" style=\"width:245px;height:auto\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/Firma.jpg 405w, https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/Firma-300x110.jpg 300w\" sizes=\"(max-width: 405px) 100vw, 405px\" \/><\/figure>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p><a href=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/05\/ES-Carta-de-Joaquina-.pdf\">T\u00e9l\u00e9chargez la lettre en anglais ici.<\/a><\/p>\n\n<p><a href=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/05\/CA-Carta-de-Joaquina-.pdf\">T\u00e9l\u00e9chargez la lettre en catalan ici.<\/a><\/p>\n\n<p><a href=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/05\/IN-Carta-de-Joaquina-.pdf\">T\u00e9l\u00e9chargez la lettre en espa\u00f1ol ici.<\/a><\/p>\n\n<p><a href=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/05\/FR-Carta-de-Joaquina-.pdf\">T\u00e9l\u00e9charger la lettre en fran\u00e7ais ici.<\/a><\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Carta a la Familia Vedruna en la fiesta del 22 de Mayo de 2024\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/OeCzqY8KynY?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Letter to the Vedruna Family on the feast of May 22, 2024\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/S6-eMdgmDs4?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Lettre \u00e0 la famille Vedruna \u00e0 l&#039;occasion de la f\u00eate du 22 mai 2024\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/GNJftPc0WyI?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Carta a la Fam\u00edlia Vedruna en la festa del 22 de Maig de 2024\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/yhVg7UpqeyE?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ch\u00e8re famille, famille, oui, nous sommes une famille, parce que chacun d&rsquo;entre nous, \u00e0 partir de nos diff\u00e9rents r\u00f4les et services, dans le m\u00eame c\u0153ur, vit et partage son exp\u00e9rience et ses appels au Bon J\u00e9sus. Cela fait quelques jours que je ne vous ai pas \u00e9crit, mais j&rsquo;ai l&rsquo;occasion de le faire \u00e0 l&rsquo;occasion [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10728,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[216],"tags":[],"class_list":["post-10750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vedruna-communication-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lettre de Joaquina \u00e0 la famille Vedruna \u00e0 l&#039;occasion de la f\u00eate du 22 mai<\/title>\n<meta name=\"description\" content=\"Ch\u00e8re famille, famille, oui, nous sommes une famille, parce que chacun d&#039;entre nous, \u00e0 partir de nos diff\u00e9rents r\u00f4les et services, dans le m\u00eame c\u0153ur, vit et partage son exp\u00e9rience et ses appels au Bon J\u00e9sus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lettre de Joaquina \u00e0 la famille Vedruna \u00e0 l&#039;occasion de la f\u00eate du 22 mai\" \/>\n<meta property=\"og:description\" content=\"Ch\u00e8re famille, famille, oui, nous sommes une famille, parce que chacun d&#039;entre nous, \u00e0 partir de nos diff\u00e9rents r\u00f4les et services, dans le m\u00eame c\u0153ur, vit et partage son exp\u00e9rience et ses appels au Bon J\u00e9sus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-20T08:11:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-23T21:18:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/05\/IMG_20230716_130742-scaled-e1716152089816.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1919\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oriana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oriana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\\\/\"},\"author\":{\"name\":\"Oriana\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/3ead809e9735eaa7b26dd6ad5f18e716\"},\"headline\":\"Lettre \u00e0 la famille Vedruna \u00e0 l&rsquo;occasion de la f\u00eate du 22 mai 2024\",\"datePublished\":\"2024-05-20T08:11:25+00:00\",\"dateModified\":\"2024-05-23T21:18:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\\\/\"},\"wordCount\":674,\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/IMG_20230716_130742-scaled-e1716152089816.jpg\",\"articleSection\":[\"Vedruna Communication\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\\\/\",\"name\":\"Lettre de Joaquina \u00e0 la famille Vedruna \u00e0 l'occasion de la f\u00eate du 22 mai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/IMG_20230716_130742-scaled-e1716152089816.jpg\",\"datePublished\":\"2024-05-20T08:11:25+00:00\",\"dateModified\":\"2024-05-23T21:18:57+00:00\",\"description\":\"Ch\u00e8re famille, famille, oui, nous sommes une famille, parce que chacun d'entre nous, \u00e0 partir de nos diff\u00e9rents r\u00f4les et services, dans le m\u00eame c\u0153ur, vit et partage son exp\u00e9rience et ses appels au Bon J\u00e9sus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vedruna.org\\\/fr\\\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/IMG_20230716_130742-scaled-e1716152089816.jpg\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/IMG_20230716_130742-scaled-e1716152089816.jpg\",\"width\":2560,\"height\":1919},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettre \u00e0 la famille Vedruna \u00e0 l&#8217;occasion de la f\u00eate du 22 mai 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"name\":\"Carmelitas de la Caridad Vedruna\",\"description\":\"Carmelitas de la caridad\",\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\",\"name\":\"Carmelitas de la caridad Vedruna\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"width\":1200,\"height\":463,\"caption\":\"Carmelitas de la caridad Vedruna\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/3ead809e9735eaa7b26dd6ad5f18e716\",\"name\":\"Oriana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g\",\"caption\":\"Oriana\"},\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/author\\\/oriana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lettre de Joaquina \u00e0 la famille Vedruna \u00e0 l'occasion de la f\u00eate du 22 mai","description":"Ch\u00e8re famille, famille, oui, nous sommes une famille, parce que chacun d'entre nous, \u00e0 partir de nos diff\u00e9rents r\u00f4les et services, dans le m\u00eame c\u0153ur, vit et partage son exp\u00e9rience et ses appels au Bon J\u00e9sus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/","og_locale":"fr_FR","og_type":"article","og_title":"Lettre de Joaquina \u00e0 la famille Vedruna \u00e0 l'occasion de la f\u00eate du 22 mai","og_description":"Ch\u00e8re famille, famille, oui, nous sommes une famille, parce que chacun d'entre nous, \u00e0 partir de nos diff\u00e9rents r\u00f4les et services, dans le m\u00eame c\u0153ur, vit et partage son exp\u00e9rience et ses appels au Bon J\u00e9sus.","og_url":"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/","og_site_name":"Carmelitas de la Caridad Vedruna","article_published_time":"2024-05-20T08:11:25+00:00","article_modified_time":"2024-05-23T21:18:57+00:00","og_image":[{"width":2560,"height":1919,"url":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/05\/IMG_20230716_130742-scaled-e1716152089816.jpg","type":"image\/jpeg"}],"author":"Oriana","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Oriana","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/#article","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/"},"author":{"name":"Oriana","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/3ead809e9735eaa7b26dd6ad5f18e716"},"headline":"Lettre \u00e0 la famille Vedruna \u00e0 l&rsquo;occasion de la f\u00eate du 22 mai 2024","datePublished":"2024-05-20T08:11:25+00:00","dateModified":"2024-05-23T21:18:57+00:00","mainEntityOfPage":{"@id":"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/"},"wordCount":674,"publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"image":{"@id":"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/05\/IMG_20230716_130742-scaled-e1716152089816.jpg","articleSection":["Vedruna Communication"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/","url":"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/","name":"Lettre de Joaquina \u00e0 la famille Vedruna \u00e0 l'occasion de la f\u00eate du 22 mai","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/#primaryimage"},"image":{"@id":"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/05\/IMG_20230716_130742-scaled-e1716152089816.jpg","datePublished":"2024-05-20T08:11:25+00:00","dateModified":"2024-05-23T21:18:57+00:00","description":"Ch\u00e8re famille, famille, oui, nous sommes une famille, parce que chacun d'entre nous, \u00e0 partir de nos diff\u00e9rents r\u00f4les et services, dans le m\u00eame c\u0153ur, vit et partage son exp\u00e9rience et ses appels au Bon J\u00e9sus.","breadcrumb":{"@id":"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/#primaryimage","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/05\/IMG_20230716_130742-scaled-e1716152089816.jpg","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/05\/IMG_20230716_130742-scaled-e1716152089816.jpg","width":2560,"height":1919},{"@type":"BreadcrumbList","@id":"https:\/\/vedruna.org\/fr\/lettre-a-la-famille-vedruna-a-loccasion-de-la-fete-du-22-mai-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vedruna.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Lettre \u00e0 la famille Vedruna \u00e0 l&#8217;occasion de la f\u00eate du 22 mai 2024"}]},{"@type":"WebSite","@id":"https:\/\/vedruna.org\/fr\/#website","url":"https:\/\/vedruna.org\/fr\/","name":"Carmelitas de la Caridad Vedruna","description":"Carmelitas de la caridad","publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vedruna.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vedruna.org\/fr\/#organization","name":"Carmelitas de la caridad Vedruna","url":"https:\/\/vedruna.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","width":1200,"height":463,"caption":"Carmelitas de la caridad Vedruna"},"image":{"@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/3ead809e9735eaa7b26dd6ad5f18e716","name":"Oriana","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g","caption":"Oriana"},"url":"https:\/\/vedruna.org\/fr\/author\/oriana\/"}]}},"_links":{"self":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/10750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/comments?post=10750"}],"version-history":[{"count":5,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/10750\/revisions"}],"predecessor-version":[{"id":10775,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/10750\/revisions\/10775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media\/10728"}],"wp:attachment":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media?parent=10750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/categories?post=10750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/tags?post=10750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}