{"id":11341,"date":"2024-06-12T09:43:13","date_gmt":"2024-06-12T07:43:13","guid":{"rendered":"https:\/\/vedruna.org\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/"},"modified":"2024-06-12T09:43:24","modified_gmt":"2024-06-12T07:43:24","slug":"protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants","status":"publish","type":"post","link":"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/","title":{"rendered":"Protection et r\u00e9habilitation : La mission du Centre Kekeli contre le travail des enfants."},"content":{"rendered":"\n<p><\/p>\n\n<p>La Journ\u00e9e mondiale contre le travail des enfants, c\u00e9l\u00e9br\u00e9e chaque 12 juin, nous rappelle l&rsquo;imp\u00e9ratif mondial d&rsquo;\u00e9liminer le travail des enfants sous toutes ses formes. Selon le rapport OIT\/UNICEF intitul\u00e9. <a href=\"https:\/\/www.unicef.es\/publicacion\/trabajo-infantil-estimaciones-2020\">\n  <em>\u00ab\u00a0Le travail des enfants : estimations mondiales pour 2020, tendances et perspectives\u00a0\u00bb, 160 millions d&rsquo;enfants dans le monde &#8211; 97 millions de gar\u00e7ons et 63 millions de filles &#8211; travaillaient au d\u00e9but de l&rsquo;ann\u00e9e 2020.<\/em>\n<\/a>160 millions d&rsquo;enfants dans le monde &#8211; 97 millions de gar\u00e7ons et 63 millions de filles &#8211; travaillaient au d\u00e9but de l&rsquo;ann\u00e9e 2020. Ce chiffre repr\u00e9sente pr\u00e8s d&rsquo;un enfant sur dix dans le monde, et parmi eux, 79 millions sont engag\u00e9s dans des travaux dangereux qui mettent en p\u00e9ril leur sant\u00e9, leur s\u00e9curit\u00e9 et leur d\u00e9veloppement moral. Et pour la premi\u00e8re fois en deux d\u00e9cennies, les progr\u00e8s se sont arr\u00eat\u00e9s, avec une augmentation absolue de 8 millions d&rsquo;enfants au travail depuis 2016. La pand\u00e9mie de COVID-19 a exacerb\u00e9 cette crise, avec la possibilit\u00e9 que 8,9 millions d&rsquo;enfants suppl\u00e9mentaires soient contraints de travailler en raison de l&rsquo;augmentation de la pauvret\u00e9 dans le monde.  <\/p>\n\n<p>Dans ce contexte, le<strong> <a href=\"http:\/\/www.centrekekeli.net\/\">Centre Kekeli<\/a><\/strong>situ\u00e9 au Togo, partage son exp\u00e9rience en mati\u00e8re d&rsquo;assistance aux enfants victimes de violences, d&rsquo;abus sexuels, d&rsquo;exploitation par le travail et de traite transfrontali\u00e8re.<\/p>\n\n<p>Les enfants victimes de traite transfrontali\u00e8re sont accueillis \u00e0 l&rsquo;a\u00e9roport par la Direction g\u00e9n\u00e9rale de la protection de l&rsquo;enfance (DGPE) et d&rsquo;autres partenaires, ou r\u00e9f\u00e9r\u00e9s par les directeurs de l&rsquo;action sociale des pr\u00e9fectures du Togo. Depuis l&rsquo;a\u00e9roport, les enfants sont conduits \u00e0 la maison de transit du centre Kekeli, o\u00f9 ils sont log\u00e9s, nourris et habill\u00e9s afin de les stabiliser avant d&rsquo;\u00eatre r\u00e9int\u00e9gr\u00e9s dans leur famille. Les enfants victimes d&rsquo;exploitation par le travail sont orient\u00e9s par des tiers ou des organisations partenaires. Le juge des enfants est inform\u00e9 de la situation de chaque enfant pris en charge et rend une ordonnance de garde temporaire. Ce processus est effectu\u00e9 par le juriste de l&rsquo;unit\u00e9 sociale du Centre.<\/p>\n\n<p>L&rsquo;aide aux enfants victimes de la traite transfrontali\u00e8re et de l&rsquo;exploitation de leur travail commence d\u00e8s le processus d&rsquo;accueil. A leur arriv\u00e9e au Centre, les enfants sont d&rsquo;abord vus \u00e0 la r\u00e9ception, o\u00f9 leur identit\u00e9 est v\u00e9rifi\u00e9e (noms, pr\u00e9noms, dates de naissance, ethnie, \u00e2ge et lieu d&rsquo;origine, entre autres donn\u00e9es). Selon les cas, les enfants peuvent \u00eatre \u00e9cout\u00e9s apr\u00e8s leur installation dans leur dortoir, ce qui leur permet d&rsquo;\u00eatre rassur\u00e9s avant la phase d&rsquo;\u00e9coute et de recueil d&rsquo;informations qui est effectu\u00e9e par les travailleurs sociaux de l&rsquo;Unit\u00e9 sociale. Il n&rsquo;est pas rare que les trafiquants aient donn\u00e9 d&rsquo;autres noms \u00e0 leurs enfants. Un soutien m\u00e9dical est ensuite apport\u00e9 pour garantir la sant\u00e9 de chaque enfant, y compris des tests de grossesse et des examens m\u00e9dicaux. Un soutien psychologique et \u00e9ducatif est \u00e9galement fourni pour assurer la r\u00e9habilitation effective des victimes.<\/p>\n\n<p>Pendant la consultation, les enfants trouvent un espace s\u00fbr et protecteur pour parler de leurs exp\u00e9riences traumatisantes, de leurs souffrances, de leurs inqui\u00e9tudes, de leurs peurs et de leurs souhaits. Cet objectif est atteint gr\u00e2ce \u00e0 des s\u00e9ances de psychoth\u00e9rapie, des groupes de discussion et une psychoth\u00e9rapie de soutien, qui leur permettent de reprendre le contr\u00f4le de leur corps, de reprendre confiance en eux, de retrouver l&rsquo;estime de soi et de retrouver un bien-\u00eatre \u00e9motionnel.<\/p>\n\n<p>Le soutien \u00e9ducatif est assur\u00e9 par les \u00e9ducateurs et animateurs de l&rsquo;unit\u00e9 \u00e9ducative \u00e0 travers des activit\u00e9s r\u00e9cr\u00e9atives, sportives, de danse et de gymnastique, ainsi que des sorties avec les victimes. Les enfants b\u00e9n\u00e9ficient d&rsquo;un soutien \u00e9ducatif pour am\u00e9liorer leur scolarit\u00e9 pendant leur s\u00e9jour dans le centre de transit, avant d&rsquo;\u00eatre r\u00e9int\u00e9gr\u00e9s dans leur famille et dans la soci\u00e9t\u00e9.<\/p>\n\n<p>La r\u00e9int\u00e9gration des enfants dans leur famille est un processus de collaboration impliquant tous les acteurs du syst\u00e8me de protection de l&rsquo;enfance, y compris les parents. Pendant son s\u00e9jour au centre de transit de Kekeli Centre, l&rsquo;unit\u00e9 sociale travaille en \u00e9troite collaboration avec les directeurs de pr\u00e9fecture (PD) et les travailleurs sociaux du minist\u00e8re de l&rsquo;action sociale dans tout le pays pour retrouver les parents des victimes. Au cours du processus de r\u00e9int\u00e9gration, des soins psychosociaux sont prodigu\u00e9s \u00e0 chaque parent en pr\u00e9sence des acteurs susmentionn\u00e9s et des acteurs locaux, afin de garantir que les enfants sont correctement r\u00e9int\u00e9gr\u00e9s et ne redeviennent pas victimes d&rsquo;exploitation. Une fois r\u00e9int\u00e9gr\u00e9s dans leur famille biologique, les enfants sont renvoy\u00e9s \u00e0 l&rsquo;\u00e9cole ou, dans le cas des adultes, sur leur lieu de travail pour les occuper. Un contact permanent est maintenu avec l&rsquo;enfant et ses parents par le biais d&rsquo;un suivi post-r\u00e9int\u00e9gration, tant dans les centres d&rsquo;apprentissage qu&rsquo;\u00e0 l&rsquo;\u00e9cole, et par l&rsquo;interm\u00e9diaire des directeurs pr\u00e9fectoraux. Ces suivis permettent de s&rsquo;assurer que les enfants sont bien int\u00e9gr\u00e9s et qu&rsquo;ils poursuivent leur scolarit\u00e9 sans heurts, en r\u00e9solvant les probl\u00e8mes qui peuvent survenir dans leur environnement.<\/p>\n\n<p>Le centre Kekeli, par l&rsquo;interm\u00e9diaire de son personnel et de ses proc\u00e9dures de soutien, fournit aux victimes des soins holistiques afin de garantir une r\u00e9adaptation efficace. Outre les soins, des initiatives de pr\u00e9vention sont mises en \u0153uvre chaque ann\u00e9e pour sensibiliser les enfants, les jeunes et les adultes \u00e0 ce probl\u00e8me, en les informant des institutions auxquelles ils peuvent s&rsquo;adresser s&rsquo;ils sont victimes ou t\u00e9moins. L&rsquo;attention est cruciale dans la lutte contre cette dure r\u00e9alit\u00e9, mais il est \u00e9galement n\u00e9cessaire de mettre en \u0153uvre des initiatives de sensibilisation pour freiner l&rsquo;exploitation des enfants par le travail et la traite, dont l&rsquo;objectif principal est d&rsquo;exploiter les enfants dans des conditions d\u00e9plorables, au m\u00e9pris de leurs droits.<\/p>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"694\" height=\"678\" data-id=\"11329\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed-4.jpg\" alt=\"\" class=\"wp-image-11329\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed-4.jpg 694w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed-4-480x469.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 694px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"412\" height=\"320\" data-id=\"11325\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed-2-1.jpg\" alt=\"\" class=\"wp-image-11325\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed-2-1.jpg 412w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed-2-1-300x233.jpg 300w\" sizes=\"(max-width: 412px) 100vw, 412px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"438\" data-id=\"11303\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed-1.jpg\" alt=\"\" class=\"wp-image-11303\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed-1.jpg 780w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed-1-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 780px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"681\" height=\"423\" data-id=\"11311\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed-3.jpg\" alt=\"\" class=\"wp-image-11311\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed-3.jpg 681w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed-3-480x298.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 681px, 100vw\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Journ\u00e9e mondiale contre le travail des enfants, c\u00e9l\u00e9br\u00e9e chaque 12 juin, nous rappelle l&rsquo;imp\u00e9ratif mondial d&rsquo;\u00e9liminer le travail des enfants sous toutes ses formes. Selon le rapport OIT\/UNICEF intitul\u00e9. \u00ab\u00a0Le travail des enfants : estimations mondiales pour 2020, tendances et perspectives\u00a0\u00bb, 160 millions d&rsquo;enfants dans le monde &#8211; 97 millions de gar\u00e7ons et 63 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11322,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[216],"tags":[],"class_list":["post-11341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vedruna-communication-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protection et r\u00e9habilitation : La mission du Centre Kekeli contre le travail des enfants<\/title>\n<meta name=\"description\" content=\"Dans le cadre du 12 juin, Journ\u00e9e mondiale contre le travail des enfants, le Centre Kekeli, situ\u00e9 au Togo, partage son exp\u00e9rience en mati\u00e8re d&#039;assistance aux enfants victimes de violences, d&#039;abus sexuels, d&#039;exploitation par le travail et de trafic transfrontalier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protection et r\u00e9habilitation : La mission du Centre Kekeli contre le travail des enfants\" \/>\n<meta property=\"og:description\" content=\"Dans le cadre du 12 juin, Journ\u00e9e mondiale contre le travail des enfants, le Centre Kekeli, situ\u00e9 au Togo, partage son exp\u00e9rience en mati\u00e8re d&#039;assistance aux enfants victimes de violences, d&#039;abus sexuels, d&#039;exploitation par le travail et de trafic transfrontalier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/\" \/>\n<meta property=\"og:site_name\" content=\"Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-12T07:43:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-12T07:43:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"665\" \/>\n\t<meta property=\"og:image:height\" content=\"499\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oriana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oriana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\\\/\"},\"author\":{\"name\":\"Oriana\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/3ead809e9735eaa7b26dd6ad5f18e716\"},\"headline\":\"Protection et r\u00e9habilitation : La mission du Centre Kekeli contre le travail des enfants.\",\"datePublished\":\"2024-06-12T07:43:13+00:00\",\"dateModified\":\"2024-06-12T07:43:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\\\/\"},\"wordCount\":1061,\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/unnamed.jpg\",\"articleSection\":[\"Vedruna Communication\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\\\/\",\"name\":\"Protection et r\u00e9habilitation : La mission du Centre Kekeli contre le travail des enfants\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/unnamed.jpg\",\"datePublished\":\"2024-06-12T07:43:13+00:00\",\"dateModified\":\"2024-06-12T07:43:24+00:00\",\"description\":\"Dans le cadre du 12 juin, Journ\u00e9e mondiale contre le travail des enfants, le Centre Kekeli, situ\u00e9 au Togo, partage son exp\u00e9rience en mati\u00e8re d'assistance aux enfants victimes de violences, d'abus sexuels, d'exploitation par le travail et de trafic transfrontalier.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vedruna.org\\\/fr\\\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/unnamed.jpg\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/unnamed.jpg\",\"width\":665,\"height\":499},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protection et r\u00e9habilitation : La mission du Centre Kekeli contre le travail des enfants.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"name\":\"Carmelitas de la Caridad Vedruna\",\"description\":\"Carmelitas de la caridad\",\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\",\"name\":\"Carmelitas de la caridad Vedruna\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"width\":1200,\"height\":463,\"caption\":\"Carmelitas de la caridad Vedruna\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/3ead809e9735eaa7b26dd6ad5f18e716\",\"name\":\"Oriana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g\",\"caption\":\"Oriana\"},\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/author\\\/oriana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protection et r\u00e9habilitation : La mission du Centre Kekeli contre le travail des enfants","description":"Dans le cadre du 12 juin, Journ\u00e9e mondiale contre le travail des enfants, le Centre Kekeli, situ\u00e9 au Togo, partage son exp\u00e9rience en mati\u00e8re d'assistance aux enfants victimes de violences, d'abus sexuels, d'exploitation par le travail et de trafic transfrontalier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/","og_locale":"fr_FR","og_type":"article","og_title":"Protection et r\u00e9habilitation : La mission du Centre Kekeli contre le travail des enfants","og_description":"Dans le cadre du 12 juin, Journ\u00e9e mondiale contre le travail des enfants, le Centre Kekeli, situ\u00e9 au Togo, partage son exp\u00e9rience en mati\u00e8re d'assistance aux enfants victimes de violences, d'abus sexuels, d'exploitation par le travail et de trafic transfrontalier.","og_url":"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/","og_site_name":"Carmelitas de la Caridad Vedruna","article_published_time":"2024-06-12T07:43:13+00:00","article_modified_time":"2024-06-12T07:43:24+00:00","og_image":[{"width":665,"height":499,"url":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed.jpg","type":"image\/jpeg"}],"author":"Oriana","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Oriana","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/#article","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/"},"author":{"name":"Oriana","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/3ead809e9735eaa7b26dd6ad5f18e716"},"headline":"Protection et r\u00e9habilitation : La mission du Centre Kekeli contre le travail des enfants.","datePublished":"2024-06-12T07:43:13+00:00","dateModified":"2024-06-12T07:43:24+00:00","mainEntityOfPage":{"@id":"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/"},"wordCount":1061,"publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"image":{"@id":"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed.jpg","articleSection":["Vedruna Communication"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/","url":"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/","name":"Protection et r\u00e9habilitation : La mission du Centre Kekeli contre le travail des enfants","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/#primaryimage"},"image":{"@id":"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed.jpg","datePublished":"2024-06-12T07:43:13+00:00","dateModified":"2024-06-12T07:43:24+00:00","description":"Dans le cadre du 12 juin, Journ\u00e9e mondiale contre le travail des enfants, le Centre Kekeli, situ\u00e9 au Togo, partage son exp\u00e9rience en mati\u00e8re d'assistance aux enfants victimes de violences, d'abus sexuels, d'exploitation par le travail et de trafic transfrontalier.","breadcrumb":{"@id":"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/#primaryimage","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed.jpg","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/06\/unnamed.jpg","width":665,"height":499},{"@type":"BreadcrumbList","@id":"https:\/\/vedruna.org\/fr\/protection-et-rehabilitation-la-mission-du-centre-kekeli-contre-le-travail-des-enfants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vedruna.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Protection et r\u00e9habilitation : La mission du Centre Kekeli contre le travail des enfants."}]},{"@type":"WebSite","@id":"https:\/\/vedruna.org\/fr\/#website","url":"https:\/\/vedruna.org\/fr\/","name":"Carmelitas de la Caridad Vedruna","description":"Carmelitas de la caridad","publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vedruna.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vedruna.org\/fr\/#organization","name":"Carmelitas de la caridad Vedruna","url":"https:\/\/vedruna.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","width":1200,"height":463,"caption":"Carmelitas de la caridad Vedruna"},"image":{"@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/3ead809e9735eaa7b26dd6ad5f18e716","name":"Oriana","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3c296f157b28de3368d865a71a57147d9800302becc0681c62476817e05d64a?s=96&d=mm&r=g","caption":"Oriana"},"url":"https:\/\/vedruna.org\/fr\/author\/oriana\/"}]}},"_links":{"self":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/11341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/comments?post=11341"}],"version-history":[{"count":1,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/11341\/revisions"}],"predecessor-version":[{"id":11342,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/11341\/revisions\/11342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media\/11322"}],"wp:attachment":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media?parent=11341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/categories?post=11341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/tags?post=11341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}