{"id":12166,"date":"2024-07-28T08:30:00","date_gmt":"2024-07-28T06:30:00","guid":{"rendered":"https:\/\/vedruna.org\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/"},"modified":"2024-07-28T09:55:24","modified_gmt":"2024-07-28T07:55:24","slug":"perou-lutte-inlassable-contre-la-traite-des-etres-humains","status":"publish","type":"post","link":"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/","title":{"rendered":"P\u00e9rou : lutte inlassable contre la traite des \u00eatres humains"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong>\u00ab\u00a0Si nous fermons les yeux et les oreilles, si nous restons inertes face \u00e0 la r\u00e9alit\u00e9 de la traite des \u00eatres humains, nous serons complices\u00a0\u00bb.<\/strong><\/p>\n\n<p class=\"has-text-align-right\"><strong>Pape Fran\u00e7ois<\/strong><\/p>\n\n<p>Le 30 juillet, Journ\u00e9e mondiale contre la traite des personnes, est la date fix\u00e9e par les Nations unies pour sensibiliser \u00e0 la situation des victimes de la traite des \u00eatres humains et pour promouvoir et prot\u00e9ger leurs droits.<\/p>\n\n<p>La traite des \u00eatres humains a d\u00e9j\u00e0 d\u00e9pass\u00e9 le trafic d&rsquo;armes en termes d&rsquo;impact et de capacit\u00e9 de nuisance sociale, et s&rsquo;est positionn\u00e9e comme la deuxi\u00e8me source de ressources \u00e9conomiques pour le crime organis\u00e9 dans le monde. C&rsquo;est un crime qui transcende les fronti\u00e8res, qui mute, s&rsquo;adapte et se propage facilement.<\/p>\n\n<p>Pour mobiliser l&rsquo;opinion publique mondiale contre ce fl\u00e9au, l&rsquo;Office des Nations unies contre la drogue <em>et le <\/em>crime (ONUDC) a lanc\u00e9 la campagne \u00a0\u00bb <strong>C\u0153ur bleu\u00a0\u00bb<\/strong>. La campagne est ouverte \u00e0 tous ceux qui souhaitent participer <em>et porter <\/em>le <strong>C\u0152UR BLEU<\/strong> comme symbole de leur soutien \u00e0 la lutte contre la traite des \u00eatres humains. Cette ann\u00e9e 2024 a pour devise <strong>: \u00ab\u00a0<em>Nous ne pouvons laisser aucun enfant de c\u00f4t\u00e9 dans la lutte contre la traite des \u00eatres humains<\/em>\u00ab\u00a0<\/strong>.<\/p>\n\n<p>Des changements substantiels dans la dynamique de la criminalit\u00e9 se sont produits depuis la pand\u00e9mie de COVID-19 et doivent \u00eatre reconnus afin d&rsquo;am\u00e9liorer la lutte contre cette forme de violation flagrante des droits de l&rsquo;homme.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Changements dans les formes de recrutement. Les formes de recrutement qui passent par le monde virtuel, les r\u00e9seaux sociaux et les jeux en ligne ont gagn\u00e9 du terrain.<\/li>\n\n\n\n<li>Changements dans les formes d&rsquo;exploitation. Aujourd&rsquo;hui, l&rsquo;exploitation sexuelle passe \u00e9galement par des plateformes en ligne, telles que <em>OnlyFans<\/em> ou autres, qui sont de <strong>nouvelles formes d&rsquo;exploitation sexuelle<\/strong> attirant de plus en plus d&rsquo;adolescents et de jeunes femmes ; elles d\u00e9veloppent les <strong>m\u00eames sch\u00e9mas que la prostitution et la pornographie<\/strong>, reproduisant la violence sexuelle \u00e0 l&rsquo;\u00e9gard des femmes, avec les formes \u00ab\u00a0les plus atroces\u00a0\u00bb de la domination masculine.<\/li>\n\n\n\n<li>Des revers dans les politiques de confrontation, dus \u00e0 l&rsquo;affaiblissement des \u00c9tats et au renforcement des strat\u00e9gies de pillage des march\u00e9s, qui ont g\u00e9n\u00e9r\u00e9 une augmentation des conditions mat\u00e9rielles et subjectives n\u00e9cessaires \u00e0 l&rsquo;accroissement de la traite des \u00eatres humains \u00e0 diff\u00e9rentes fins d&rsquo;exploitation et un affaiblissement des politiques publiques et des possibilit\u00e9s d&rsquo;action de la soci\u00e9t\u00e9 civile pour mener \u00e0 bien la lutte contre la traite des \u00eatres humains.<\/li>\n<\/ul>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image alignright size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"608\" data-id=\"12087\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/07\/IMG_20240717_083101-1024x608.jpg\" alt=\"\" class=\"wp-image-12087\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/07\/IMG_20240717_083101-980x582.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/07\/IMG_20240717_083101-480x285.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"563\" data-id=\"12091\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/07\/IMG_20240716_182633.jpg\" alt=\"\" class=\"wp-image-12091\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/07\/IMG_20240716_182633.jpg 1000w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/07\/IMG_20240716_182633-980x552.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/07\/IMG_20240716_182633-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/><\/figure>\n<\/figure>\n\n<p>Au P\u00e9rou, notre Congr\u00e9gation est s\u00e9rieusement engag\u00e9e dans la lutte contre ce fl\u00e9au, qui <em>mine le tissu social au plus profond<\/em> et affecte les victimes qui en souffrent de telle sorte que de nombreux et grands efforts sont n\u00e9cessaires pour garantir la survie des personnes touch\u00e9es par ce crime cruel.<\/p>\n\n<p>La Congr\u00e9gation fait partie du <strong><a href=\"http:\/\/confar.org.ar\/espacios\/red-kawsay\/\">R\u00e9seau Kawsay<\/a>, <\/strong>Commission permanente de la CONFER (Conf\u00e9rence des Religieux du P\u00e9rou) et c&rsquo;est \u00e0 travers lui, dans un r\u00e9seau de r\u00e9seaux avec CLAR, <a href=\"https:\/\/www.talithakum.info\/es\">Talitha Kum International<\/a>, Observa la Trata, Red Clamor et d&rsquo;autres organisations nationales et internationales, que nous g\u00e9n\u00e9rons diff\u00e9rents espaces pour faire face \u00e0 cette r\u00e9alit\u00e9 crue.<\/p>\n\n<p>Red Kawsay travaille dans quatre domaines : la pr\u00e9vention, la sensibilisation et la formation, le plaidoyer, l&rsquo;accompagnement et la prise en charge des victimes et des survivants. En tant que s\u0153urs, nous sommes directement impliqu\u00e9es dans les dimensions de la pr\u00e9vention, de la sensibilisation, de la formation et du plaidoyer, et nous soutenons parfois l&rsquo;accompagnement et les soins aux victimes et aux survivants.<\/p>\n\n<p>Dans la jungle, dans les hameaux et les villages riverains du Moyen Ucayali, o\u00f9 nous r\u00e9alisons notre mission d&rsquo;accompagnement pastoral et social, nous menons un travail permanent avec les habitants et, plus particuli\u00e8rement, avec les \u00e9l\u00e8ves des \u00e9coles et des centres \u00e9ducatifs.<\/p>\n\n<p>Les trafiquants ne dorment pas, c&rsquo;est pourquoi nous ne baissons pas la garde face \u00e0 ce fl\u00e9au qui vole des r\u00eaves et d\u00e9truit des vies.<\/p>\n\n<p>Avec tous ceux qui luttent pour la dignit\u00e9, nous disons : <strong>STOP \u00c0 LA TRAITE DES HUMAINS !<\/strong><\/p>\n\n<p class=\"has-text-align-right\"><strong>Sr. Isabel Migu\u00e9lez, CCV<\/strong><\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"> \n<iframe loading=\"lazy\" title=\"30 JUL 2024 TRABAJO VEDRUNA EN PERU CONTRA LA TRATA DE PERSONAS\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/fV-saDxjfms?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n <\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Si nous fermons les yeux et les oreilles, si nous restons inertes face \u00e0 la r\u00e9alit\u00e9 de la traite des \u00eatres humains, nous serons complices\u00a0\u00bb. Pape Fran\u00e7ois Le 30 juillet, Journ\u00e9e mondiale contre la traite des personnes, est la date fix\u00e9e par les Nations unies pour sensibiliser \u00e0 la situation des victimes de la traite [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12098,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[155,216,146],"tags":[],"class_list":["post-12166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-perou","category-vedruna-communication-fr","category-vedrunamerica-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>P\u00e9rou : lutte inlassable contre la traite des \u00eatres humains<\/title>\n<meta name=\"description\" content=\"Le 30 juillet, Journ\u00e9e mondiale contre la traite des personnes, est la date fix\u00e9e par les Nations unies pour sensibiliser \u00e0 la situation des victimes de la traite des \u00eatres humains et pour promouvoir et prot\u00e9ger leurs droits.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P\u00e9rou : lutte inlassable contre la traite des \u00eatres humains\" \/>\n<meta property=\"og:description\" content=\"Le 30 juillet, Journ\u00e9e mondiale contre la traite des personnes, est la date fix\u00e9e par les Nations unies pour sensibiliser \u00e0 la situation des victimes de la traite des \u00eatres humains et pour promouvoir et prot\u00e9ger leurs droits.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/\" \/>\n<meta property=\"og:site_name\" content=\"Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-28T06:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-28T07:55:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/07\/IMG_20240716_101049-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3n Vedrunam\u00e9rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3n Vedrunam\u00e9rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\\\/\"},\"author\":{\"name\":\"Comunicaci\u00f3n Vedrunam\u00e9rica\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/cf468646189533fb6a3aae475663fdc7\"},\"headline\":\"P\u00e9rou : lutte inlassable contre la traite des \u00eatres humains\",\"datePublished\":\"2024-07-28T06:30:00+00:00\",\"dateModified\":\"2024-07-28T07:55:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\\\/\"},\"wordCount\":731,\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/IMG_20240716_101049-1-scaled.jpg\",\"articleSection\":[\"P\u00e9rou\",\"Vedruna Communication\",\"Vedrunamerica\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\\\/\",\"name\":\"P\u00e9rou : lutte inlassable contre la traite des \u00eatres humains\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/IMG_20240716_101049-1-scaled.jpg\",\"datePublished\":\"2024-07-28T06:30:00+00:00\",\"dateModified\":\"2024-07-28T07:55:24+00:00\",\"description\":\"Le 30 juillet, Journ\u00e9e mondiale contre la traite des personnes, est la date fix\u00e9e par les Nations unies pour sensibiliser \u00e0 la situation des victimes de la traite des \u00eatres humains et pour promouvoir et prot\u00e9ger leurs droits.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vedruna.org\\\/fr\\\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/IMG_20240716_101049-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/IMG_20240716_101049-1-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"P\u00e9rou : lutte inlassable contre la traite des \u00eatres humains\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"name\":\"Carmelitas de la Caridad Vedruna\",\"description\":\"Carmelitas de la caridad\",\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\",\"name\":\"Carmelitas de la caridad Vedruna\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"width\":1200,\"height\":463,\"caption\":\"Carmelitas de la caridad Vedruna\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/cf468646189533fb6a3aae475663fdc7\",\"name\":\"Comunicaci\u00f3n Vedrunam\u00e9rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3n Vedrunam\u00e9rica\"},\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/author\\\/comunicacion-vedrunamerica\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P\u00e9rou : lutte inlassable contre la traite des \u00eatres humains","description":"Le 30 juillet, Journ\u00e9e mondiale contre la traite des personnes, est la date fix\u00e9e par les Nations unies pour sensibiliser \u00e0 la situation des victimes de la traite des \u00eatres humains et pour promouvoir et prot\u00e9ger leurs droits.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/","og_locale":"fr_FR","og_type":"article","og_title":"P\u00e9rou : lutte inlassable contre la traite des \u00eatres humains","og_description":"Le 30 juillet, Journ\u00e9e mondiale contre la traite des personnes, est la date fix\u00e9e par les Nations unies pour sensibiliser \u00e0 la situation des victimes de la traite des \u00eatres humains et pour promouvoir et prot\u00e9ger leurs droits.","og_url":"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/","og_site_name":"Carmelitas de la Caridad Vedruna","article_published_time":"2024-07-28T06:30:00+00:00","article_modified_time":"2024-07-28T07:55:24+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/07\/IMG_20240716_101049-1-scaled.jpg","type":"image\/jpeg"}],"author":"Comunicaci\u00f3n Vedrunam\u00e9rica","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Comunicaci\u00f3n Vedrunam\u00e9rica","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/#article","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/"},"author":{"name":"Comunicaci\u00f3n Vedrunam\u00e9rica","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/cf468646189533fb6a3aae475663fdc7"},"headline":"P\u00e9rou : lutte inlassable contre la traite des \u00eatres humains","datePublished":"2024-07-28T06:30:00+00:00","dateModified":"2024-07-28T07:55:24+00:00","mainEntityOfPage":{"@id":"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/"},"wordCount":731,"publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"image":{"@id":"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/07\/IMG_20240716_101049-1-scaled.jpg","articleSection":["P\u00e9rou","Vedruna Communication","Vedrunamerica"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/","url":"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/","name":"P\u00e9rou : lutte inlassable contre la traite des \u00eatres humains","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/#primaryimage"},"image":{"@id":"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/07\/IMG_20240716_101049-1-scaled.jpg","datePublished":"2024-07-28T06:30:00+00:00","dateModified":"2024-07-28T07:55:24+00:00","description":"Le 30 juillet, Journ\u00e9e mondiale contre la traite des personnes, est la date fix\u00e9e par les Nations unies pour sensibiliser \u00e0 la situation des victimes de la traite des \u00eatres humains et pour promouvoir et prot\u00e9ger leurs droits.","breadcrumb":{"@id":"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/#primaryimage","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/07\/IMG_20240716_101049-1-scaled.jpg","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/07\/IMG_20240716_101049-1-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/vedruna.org\/fr\/perou-lutte-inlassable-contre-la-traite-des-etres-humains\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vedruna.org\/fr\/"},{"@type":"ListItem","position":2,"name":"P\u00e9rou : lutte inlassable contre la traite des \u00eatres humains"}]},{"@type":"WebSite","@id":"https:\/\/vedruna.org\/fr\/#website","url":"https:\/\/vedruna.org\/fr\/","name":"Carmelitas de la Caridad Vedruna","description":"Carmelitas de la caridad","publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vedruna.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vedruna.org\/fr\/#organization","name":"Carmelitas de la caridad Vedruna","url":"https:\/\/vedruna.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","width":1200,"height":463,"caption":"Carmelitas de la caridad Vedruna"},"image":{"@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/cf468646189533fb6a3aae475663fdc7","name":"Comunicaci\u00f3n Vedrunam\u00e9rica","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g","caption":"Comunicaci\u00f3n Vedrunam\u00e9rica"},"url":"https:\/\/vedruna.org\/fr\/author\/comunicacion-vedrunamerica\/"}]}},"_links":{"self":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/12166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/comments?post=12166"}],"version-history":[{"count":1,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/12166\/revisions"}],"predecessor-version":[{"id":12167,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/12166\/revisions\/12167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media\/12098"}],"wp:attachment":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media?parent=12166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/categories?post=12166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/tags?post=12166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}