{"id":14089,"date":"2024-10-18T12:05:20","date_gmt":"2024-10-18T10:05:20","guid":{"rendered":"https:\/\/vedruna.org\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/"},"modified":"2024-10-18T12:05:32","modified_gmt":"2024-10-18T10:05:32","slug":"nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie","status":"publish","type":"post","link":"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/","title":{"rendered":"Nouveau coordinateur r\u00e9gional au Br\u00e9sil : \u00ab\u00a0\u00catre une pr\u00e9sence d&rsquo;espoir et de proph\u00e9tie\u00a0\u00bb."},"content":{"rendered":"\n<p>Lors de la Conf\u00e9rence des religieux et religieuses du Br\u00e9sil (CRB) qui s&rsquo;est tenue en septembre 2024, notre <strong>s\u0153ur Veronica Terezinha Hergesell<\/strong> <strong>a \u00e9t\u00e9 \u00e9lue coordinatrice de la r\u00e9gion de Palmas Tocantins<\/strong>. Cette r\u00e9union a rassembl\u00e9 des membres de diverses congr\u00e9gations pour renouveler leur engagement dans la vie consacr\u00e9e et la mission \u00e9vang\u00e9lisatrice dans le pays, et a marqu\u00e9 le d\u00e9but d&rsquo;une p\u00e9riode de coordination de trois ans pour notre s\u0153ur.   <\/p>\n\n<p>Veronica assume cette t\u00e2che avec son <strong>\u00e9quipe inter-congr\u00e9gationnelle<\/strong>, compos\u00e9e des s\u0153urs Marizete Queiroz de Souza, de la Congr\u00e9gation du Saint-Sacrement, Maria de Jesus Ferreira da Silva, des Dominicains de Notre-Dame du Rosaire de Monteils, et Anair Maria Loro, de Notre-Dame.  <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"914\" height=\"531\" data-id=\"14078\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/CRB.jpg\" alt=\"\" class=\"wp-image-14078\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/CRB.jpg 914w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/CRB-480x279.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 914px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"826\" height=\"562\" data-id=\"14074\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/CRB-2.jpg\" alt=\"\" class=\"wp-image-14074\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/CRB-2.jpg 826w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/CRB-2-480x327.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 826px, 100vw\" \/><\/figure>\n<\/figure>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Comme il est de coutume au Br\u00e9sil, apr\u00e8s les assembl\u00e9es des 20 centres r\u00e9gionaux de la CRB, une <strong>r\u00e9union de formation<\/strong> a \u00e9t\u00e9 organis\u00e9e pour mettre \u00e0 jour les coordinateurs \u00e9lus sur la r\u00e9alit\u00e9 de la conf\u00e9rence nationale. S\u0153ur Veronica a particip\u00e9 \u00e0 cette r\u00e9union les 14, 15 et 16 octobre, o\u00f9 elle a pu pr\u00e9parer la mission qu&rsquo;elle entreprendra ces prochaines ann\u00e9es avec son \u00e9quipe.   <\/p>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"553\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-17-at-22.47.57-1024x553.jpeg\" alt=\"\" class=\"wp-image-14065\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-17-at-22.47.57-980x530.jpeg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-17-at-22.47.57-480x259.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Le fait d&rsquo;\u00eatre le coordinateur r\u00e9gional de la Conf\u00e9rence br\u00e9silienne des religieux et religieuses implique :  <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Animer la vie religieuse consacr\u00e9e dans la r\u00e9gion de Palmas, Tocantins.<\/li>\n\n\n\n<li>Accompagner et dynamiser la vie religieuse consacr\u00e9e dans les 8 centres r\u00e9gionaux.  <\/li>\n\n\n\n<li>Visiter les communaut\u00e9s religieuses de la r\u00e9gion. \u00c0 l&rsquo;heure actuelle, il y a 225 religieux dans un total de 52 communaut\u00e9s de 62 congr\u00e9gations diff\u00e9rentes. <\/li>\n\n\n\n<li>\u00catre une pr\u00e9sence d&rsquo;espoir et de proph\u00e9tie.<\/li>\n<\/ul>\n\n<p>La R\u00e9gion Palmas Tocantins, fond\u00e9e en 1996, a eu d\u00e8s le d\u00e9part un <strong>esprit de solidarit\u00e9, d&rsquo;accueil et de soutien \u00e0<\/strong> toutes les communaut\u00e9s, en particulier celles qui sont en difficult\u00e9. Ce caract\u00e8re est toujours pr\u00e9sent aujourd&rsquo;hui et s&rsquo;exprime dans les objectifs fix\u00e9s par l&rsquo;\u00e9quipe r\u00e9gionale pour les trois prochaines ann\u00e9es :   <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Articuler et renforcer les 8 centres de la Conf\u00e9rence br\u00e9silienne des religieux et religieuses dans le Tocantins.<\/li>\n\n\n\n<li>Visitez toutes les communaut\u00e9s.  <\/li>\n\n\n\n<li>Encourager la formation continue, en organisant des r\u00e9unions en ligne tous les deux mois, dont le contenu est recommand\u00e9 par les religieux.<\/li>\n\n\n\n<li>Accompagnez la communaut\u00e9 intercongr\u00e9gationnelle qui vit aux c\u00f4t\u00e9s des indig\u00e8nes de la tribu Xerente.<\/li>\n\n\n\n<li>Inciter le CRR \u00e0 r\u00e9fl\u00e9chir et \u00e0 vivre dans une dimension de synodalit\u00e9 au sein des congr\u00e9gations et de l&rsquo;\u00c9glise.<\/li>\n<\/ul>\n\n<p>C&rsquo;est une bonne nouvelle que le <strong>charisme de Vedruna <\/strong>puisse impr\u00e9gner la r\u00e9alit\u00e9 de la r\u00e9gion de Palmas Tocantins \u00e0 travers notre s\u0153ur Veronica, qui se propose d&rsquo;animer la vie religieuse consacr\u00e9e, dans la dimension de la <strong>mystique, de la proph\u00e9tie et de l&rsquo;esp\u00e9rance<\/strong>. Elle aide aussi \u00e0 la formation permanente des religieux, \u00e0 la r\u00e9flexion et \u00e0 la recherche commune de la durabilit\u00e9. L&rsquo;esprit de Sainte Joaquina sera pr\u00e9sent en encourageant la vie religieuse consacr\u00e9e \u00e0 s&rsquo;impliquer davantage dans le monde de la pauvret\u00e9, des fronti\u00e8res humaines, des peuples indig\u00e8nes et des autres cris de cette grande Amazonie ; ainsi qu&rsquo;en offrant des opportunit\u00e9s aux religieux de vivre joyeusement leur engagement au service du Royaume.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lors de la Conf\u00e9rence des religieux et religieuses du Br\u00e9sil (CRB) qui s&rsquo;est tenue en septembre 2024, notre s\u0153ur Veronica Terezinha Hergesell a \u00e9t\u00e9 \u00e9lue coordinatrice de la r\u00e9gion de Palmas Tocantins. Cette r\u00e9union a rassembl\u00e9 des membres de diverses congr\u00e9gations pour renouveler leur engagement dans la vie consacr\u00e9e et la mission \u00e9vang\u00e9lisatrice dans le [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":14072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[145,146],"tags":[],"class_list":["post-14089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bresil","category-vedrunamerica-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouveau coordinateur r\u00e9gional au Br\u00e9sil : &quot;\u00catre une pr\u00e9sence d&#039;espoir et de proph\u00e9tie&quot;. - Carmelitas de la Caridad Vedruna<\/title>\n<meta name=\"description\" content=\"Notre s\u0153ur Veronica Hergesell sera charg\u00e9e de la coordination de la r\u00e9gion Palmas Tocantins au Br\u00e9sil pour les trois prochaines ann\u00e9es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouveau coordinateur r\u00e9gional au Br\u00e9sil : &quot;\u00catre une pr\u00e9sence d&#039;espoir et de proph\u00e9tie&quot;. - Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"og:description\" content=\"Notre s\u0153ur Veronica Hergesell sera charg\u00e9e de la coordination de la r\u00e9gion Palmas Tocantins au Br\u00e9sil pour les trois prochaines ann\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/\" \/>\n<meta property=\"og:site_name\" content=\"Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-18T10:05:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-18T10:05:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-17-at-22.47.57-1-e1729244858920.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1515\" \/>\n\t<meta property=\"og:image:height\" content=\"1041\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maria Agustina G\u00f3mez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Agustina G\u00f3mez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\\\/\"},\"author\":{\"name\":\"Maria Agustina G\u00f3mez\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/95fe789adf27c2831fc5a049c727edf5\"},\"headline\":\"Nouveau coordinateur r\u00e9gional au Br\u00e9sil : \u00ab\u00a0\u00catre une pr\u00e9sence d&rsquo;espoir et de proph\u00e9tie\u00a0\u00bb.\",\"datePublished\":\"2024-10-18T10:05:20+00:00\",\"dateModified\":\"2024-10-18T10:05:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\\\/\"},\"wordCount\":578,\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-17-at-22.47.57-1-e1729244858920.jpeg\",\"articleSection\":[\"Br\u00e9sil\",\"Vedrunamerica\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\\\/\",\"name\":\"Nouveau coordinateur r\u00e9gional au Br\u00e9sil : \\\"\u00catre une pr\u00e9sence d'espoir et de proph\u00e9tie\\\". - Carmelitas de la Caridad Vedruna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-17-at-22.47.57-1-e1729244858920.jpeg\",\"datePublished\":\"2024-10-18T10:05:20+00:00\",\"dateModified\":\"2024-10-18T10:05:32+00:00\",\"description\":\"Notre s\u0153ur Veronica Hergesell sera charg\u00e9e de la coordination de la r\u00e9gion Palmas Tocantins au Br\u00e9sil pour les trois prochaines ann\u00e9es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vedruna.org\\\/fr\\\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-17-at-22.47.57-1-e1729244858920.jpeg\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-17-at-22.47.57-1-e1729244858920.jpeg\",\"width\":1515,\"height\":1041},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouveau coordinateur r\u00e9gional au Br\u00e9sil : \u00ab\u00a0\u00catre une pr\u00e9sence d&rsquo;espoir et de proph\u00e9tie\u00a0\u00bb.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"name\":\"Carmelitas de la Caridad Vedruna\",\"description\":\"Carmelitas de la caridad\",\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\",\"name\":\"Carmelitas de la caridad Vedruna\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"width\":1200,\"height\":463,\"caption\":\"Carmelitas de la caridad Vedruna\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/95fe789adf27c2831fc5a049c727edf5\",\"name\":\"Maria Agustina G\u00f3mez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g\",\"caption\":\"Maria Agustina G\u00f3mez\"},\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/author\\\/agustina-gomez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouveau coordinateur r\u00e9gional au Br\u00e9sil : \"\u00catre une pr\u00e9sence d'espoir et de proph\u00e9tie\". - Carmelitas de la Caridad Vedruna","description":"Notre s\u0153ur Veronica Hergesell sera charg\u00e9e de la coordination de la r\u00e9gion Palmas Tocantins au Br\u00e9sil pour les trois prochaines ann\u00e9es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouveau coordinateur r\u00e9gional au Br\u00e9sil : \"\u00catre une pr\u00e9sence d'espoir et de proph\u00e9tie\". - Carmelitas de la Caridad Vedruna","og_description":"Notre s\u0153ur Veronica Hergesell sera charg\u00e9e de la coordination de la r\u00e9gion Palmas Tocantins au Br\u00e9sil pour les trois prochaines ann\u00e9es.","og_url":"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/","og_site_name":"Carmelitas de la Caridad Vedruna","article_published_time":"2024-10-18T10:05:20+00:00","article_modified_time":"2024-10-18T10:05:32+00:00","og_image":[{"width":1515,"height":1041,"url":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-17-at-22.47.57-1-e1729244858920.jpeg","type":"image\/jpeg"}],"author":"Maria Agustina G\u00f3mez","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Maria Agustina G\u00f3mez","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/#article","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/"},"author":{"name":"Maria Agustina G\u00f3mez","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/95fe789adf27c2831fc5a049c727edf5"},"headline":"Nouveau coordinateur r\u00e9gional au Br\u00e9sil : \u00ab\u00a0\u00catre une pr\u00e9sence d&rsquo;espoir et de proph\u00e9tie\u00a0\u00bb.","datePublished":"2024-10-18T10:05:20+00:00","dateModified":"2024-10-18T10:05:32+00:00","mainEntityOfPage":{"@id":"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/"},"wordCount":578,"publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"image":{"@id":"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-17-at-22.47.57-1-e1729244858920.jpeg","articleSection":["Br\u00e9sil","Vedrunamerica"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/","url":"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/","name":"Nouveau coordinateur r\u00e9gional au Br\u00e9sil : \"\u00catre une pr\u00e9sence d'espoir et de proph\u00e9tie\". - Carmelitas de la Caridad Vedruna","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/#primaryimage"},"image":{"@id":"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-17-at-22.47.57-1-e1729244858920.jpeg","datePublished":"2024-10-18T10:05:20+00:00","dateModified":"2024-10-18T10:05:32+00:00","description":"Notre s\u0153ur Veronica Hergesell sera charg\u00e9e de la coordination de la r\u00e9gion Palmas Tocantins au Br\u00e9sil pour les trois prochaines ann\u00e9es.","breadcrumb":{"@id":"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/#primaryimage","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-17-at-22.47.57-1-e1729244858920.jpeg","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-17-at-22.47.57-1-e1729244858920.jpeg","width":1515,"height":1041},{"@type":"BreadcrumbList","@id":"https:\/\/vedruna.org\/fr\/nouveau-coordinateur-regional-au-bresil-etre-une-presence-despoir-et-de-prophetie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vedruna.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouveau coordinateur r\u00e9gional au Br\u00e9sil : \u00ab\u00a0\u00catre une pr\u00e9sence d&rsquo;espoir et de proph\u00e9tie\u00a0\u00bb."}]},{"@type":"WebSite","@id":"https:\/\/vedruna.org\/fr\/#website","url":"https:\/\/vedruna.org\/fr\/","name":"Carmelitas de la Caridad Vedruna","description":"Carmelitas de la caridad","publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vedruna.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vedruna.org\/fr\/#organization","name":"Carmelitas de la caridad Vedruna","url":"https:\/\/vedruna.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","width":1200,"height":463,"caption":"Carmelitas de la caridad Vedruna"},"image":{"@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/95fe789adf27c2831fc5a049c727edf5","name":"Maria Agustina G\u00f3mez","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g","caption":"Maria Agustina G\u00f3mez"},"url":"https:\/\/vedruna.org\/fr\/author\/agustina-gomez\/"}]}},"_links":{"self":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/14089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/comments?post=14089"}],"version-history":[{"count":1,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/14089\/revisions"}],"predecessor-version":[{"id":14090,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/14089\/revisions\/14090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media\/14072"}],"wp:attachment":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media?parent=14089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/categories?post=14089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/tags?post=14089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}