{"id":14522,"date":"2024-11-11T11:05:47","date_gmt":"2024-11-11T10:05:47","guid":{"rendered":"https:\/\/vedruna.org\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/"},"modified":"2024-11-11T11:06:03","modified_gmt":"2024-11-11T10:06:03","slug":"la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil","status":"publish","type":"post","link":"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/","title":{"rendered":"\u00ab\u00a0La fragilit\u00e9 de la jeunesse est la force de la transformation sociale\u00a0\u00bb &#8211; Journ\u00e9e nationale de la jeunesse au Br\u00e9sil"},"content":{"rendered":"\n<p>Des jeunes du sud, du nord, de l&rsquo;est et de l&rsquo;ouest, venus de diff\u00e9rentes localit\u00e9s, se sont r\u00e9unis pour c\u00e9l\u00e9brer la <strong>Journ\u00e9e nationale de la jeunesse (JNJ)<\/strong>, qui s&rsquo;est d\u00e9roul\u00e9e les 26 et 27 octobre \u00e0 Carnaubeira da Penha, dans l&rsquo;\u00c9tat de Pernambouc, au Br\u00e9sil.<\/p>\n\n<p>L&rsquo;\u00e9v\u00e9nement a rassembl\u00e9 plus de <strong>350 jeunes de 12 paroisses<\/strong> du dioc\u00e8se de Floresta.<\/p>\n\n<p>Le th\u00e8me du DNJ \u00e9tait <strong>\u00ab\u00a0Dans la fragilit\u00e9 de la jeunesse, la force de la transformation sociale\u00a0\u00bb,<\/strong> abord\u00e9 \u00e0 travers divers sous-th\u00e8mes tels que la jeunesse et la fragilit\u00e9, vivre la foi face aux d\u00e9fis de la vie, s&rsquo;ouvrir aux nouveaut\u00e9s de Dieu, dans les relations humaines.<\/p>\n\n<p>Ces th\u00e8mes ont fait l&rsquo;objet d&rsquo;une r\u00e9flexion dans les communaut\u00e9s et les paroisses en pr\u00e9paration de cette rencontre de jeunes tant attendue. Comme l&rsquo;a mentionn\u00e9 Dom Gabriel, <em>\u00ab\u00a0elle a r\u00e9veill\u00e9 les d\u00e9sirs, les joies, les r\u00eaves, l&rsquo;\u00e9nergie et les vibrations que chaque jeune porte en lui\u00a0\u00bb.<\/em> <\/p>\n\n<p>La dimension missionnaire du DNJ a \u00e9t\u00e9 inspir\u00e9e par les paroles du pape Fran\u00e7ois dans <a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/encyclicals\/documents\/papa-francesco_20201003_enciclica-fratelli-tutti.html\">Fratelli Tutti<\/a>, qui pr\u00f4ne la fraternit\u00e9 et l&rsquo;amiti\u00e9 sociale face aux maux qui menacent la paix et la coh\u00e9sion dans le monde, emp\u00eachant la construction d&rsquo;une soci\u00e9t\u00e9 plus solidaire et inclusive : \u00ab\u00a0nous sommes tous fr\u00e8res et s\u0153urs\u00a0\u00bb. La mission dans les communaut\u00e9s a \u00e9t\u00e9 une exp\u00e9rience enrichissante pour les jeunes, comme en t\u00e9moignent leurs t\u00e9moignages. <\/p>\n\n<p>A la fin de la mission, nous avons c\u00e9l\u00e9br\u00e9 une Eucharistie pr\u00e9sid\u00e9e par l&rsquo;\u00e9v\u00eaque Dom Gabriel, accompagn\u00e9 de cinq autres pr\u00eatres conc\u00e9l\u00e9brants.<\/p>\n\n<p>Elle a conclu par le t\u00e9moignage d&rsquo;une jeune femme :<\/p>\n\n<blockquote class=\"wp-block-quote has-medium-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab\u00a0Notre paroisse n&rsquo;est pas riche en ressources, mais elle est abondante en accueil, en partage et en foi. Continuons toujours \u00e0 nous laisser guider par la foi, la force du travail et la lumi\u00e8re de l&rsquo;esp\u00e9rance.<\/em><\/p>\n<\/blockquote>\n\n<p class=\"has-text-align-right\"><strong>Sr. Mar\u00eda L\u00f3pez Otero, CCV<\/strong><\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"14347\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0006-1024x576.jpg\" alt=\"\" class=\"wp-image-14347\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0006-980x551.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0006-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"812\" height=\"1024\" data-id=\"14339\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0014-812x1024.jpg\" alt=\"\" class=\"wp-image-14339\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0014-812x1024.jpg 812w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0014-480x605.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 812px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"14343\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0015-1024x576.jpg\" alt=\"\" class=\"wp-image-14343\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0015-1024x576.jpg 1024w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0015-980x551.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0015-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14355\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0016-1024x768.jpg\" alt=\"\" class=\"wp-image-14355\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0016-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0016-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14351\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0018-1024x768.jpg\" alt=\"\" class=\"wp-image-14351\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0018-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241103-WA0018-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Des jeunes du sud, du nord, de l&rsquo;est et de l&rsquo;ouest, venus de diff\u00e9rentes localit\u00e9s, se sont r\u00e9unis pour c\u00e9l\u00e9brer la Journ\u00e9e nationale de la jeunesse (JNJ), qui s&rsquo;est d\u00e9roul\u00e9e les 26 et 27 octobre \u00e0 Carnaubeira da Penha, dans l&rsquo;\u00c9tat de Pernambouc, au Br\u00e9sil. L&rsquo;\u00e9v\u00e9nement a rassembl\u00e9 plus de 350 jeunes de 12 paroisses [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":14338,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[145,81,146],"tags":[],"class_list":["post-14522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bresil","category-non-classifiee","category-vedrunamerica-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;La fragilit\u00e9 de la jeunesse est la force de la transformation sociale&quot; - Journ\u00e9e nationale de la jeunesse au Br\u00e9sil - Carmelitas de la Caridad Vedruna<\/title>\n<meta name=\"description\" content=\"Plus de 350 jeunes de 12 paroisses se sont r\u00e9unis les 26 et 27 octobre pour r\u00e9fl\u00e9chir ensemble sur la foi, la fraternit\u00e9 et l&#039;esp\u00e9rance.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;La fragilit\u00e9 de la jeunesse est la force de la transformation sociale&quot; - Journ\u00e9e nationale de la jeunesse au Br\u00e9sil - Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"og:description\" content=\"Plus de 350 jeunes de 12 paroisses se sont r\u00e9unis les 26 et 27 octobre pour r\u00e9fl\u00e9chir ensemble sur la foi, la fraternit\u00e9 et l&#039;esp\u00e9rance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/\" \/>\n<meta property=\"og:site_name\" content=\"Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-11T10:05:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-11T10:06:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/principal-e1730801141567.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1394\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3n Vedrunam\u00e9rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3n Vedrunam\u00e9rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\\\/\"},\"author\":{\"name\":\"Comunicaci\u00f3n Vedrunam\u00e9rica\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/cf468646189533fb6a3aae475663fdc7\"},\"headline\":\"\u00ab\u00a0La fragilit\u00e9 de la jeunesse est la force de la transformation sociale\u00a0\u00bb &#8211; Journ\u00e9e nationale de la jeunesse au Br\u00e9sil\",\"datePublished\":\"2024-11-11T10:05:47+00:00\",\"dateModified\":\"2024-11-11T10:06:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\\\/\"},\"wordCount\":372,\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/principal-e1730801141567.jpg\",\"articleSection\":[\"Br\u00e9sil\",\"Non classifi\u00e9(e)\",\"Vedrunamerica\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\\\/\",\"name\":\"\\\"La fragilit\u00e9 de la jeunesse est la force de la transformation sociale\\\" - Journ\u00e9e nationale de la jeunesse au Br\u00e9sil - Carmelitas de la Caridad Vedruna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/principal-e1730801141567.jpg\",\"datePublished\":\"2024-11-11T10:05:47+00:00\",\"dateModified\":\"2024-11-11T10:06:03+00:00\",\"description\":\"Plus de 350 jeunes de 12 paroisses se sont r\u00e9unis les 26 et 27 octobre pour r\u00e9fl\u00e9chir ensemble sur la foi, la fraternit\u00e9 et l'esp\u00e9rance.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vedruna.org\\\/fr\\\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/principal-e1730801141567.jpg\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/principal-e1730801141567.jpg\",\"width\":1394,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00a0La fragilit\u00e9 de la jeunesse est la force de la transformation sociale\u00a0\u00bb &#8211; Journ\u00e9e nationale de la jeunesse au Br\u00e9sil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"name\":\"Carmelitas de la Caridad Vedruna\",\"description\":\"Carmelitas de la caridad\",\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\",\"name\":\"Carmelitas de la caridad Vedruna\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"width\":1200,\"height\":463,\"caption\":\"Carmelitas de la caridad Vedruna\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/cf468646189533fb6a3aae475663fdc7\",\"name\":\"Comunicaci\u00f3n Vedrunam\u00e9rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3n Vedrunam\u00e9rica\"},\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/author\\\/comunicacion-vedrunamerica\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"La fragilit\u00e9 de la jeunesse est la force de la transformation sociale\" - Journ\u00e9e nationale de la jeunesse au Br\u00e9sil - Carmelitas de la Caridad Vedruna","description":"Plus de 350 jeunes de 12 paroisses se sont r\u00e9unis les 26 et 27 octobre pour r\u00e9fl\u00e9chir ensemble sur la foi, la fraternit\u00e9 et l'esp\u00e9rance.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/","og_locale":"fr_FR","og_type":"article","og_title":"\"La fragilit\u00e9 de la jeunesse est la force de la transformation sociale\" - Journ\u00e9e nationale de la jeunesse au Br\u00e9sil - Carmelitas de la Caridad Vedruna","og_description":"Plus de 350 jeunes de 12 paroisses se sont r\u00e9unis les 26 et 27 octobre pour r\u00e9fl\u00e9chir ensemble sur la foi, la fraternit\u00e9 et l'esp\u00e9rance.","og_url":"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/","og_site_name":"Carmelitas de la Caridad Vedruna","article_published_time":"2024-11-11T10:05:47+00:00","article_modified_time":"2024-11-11T10:06:03+00:00","og_image":[{"width":1394,"height":900,"url":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/principal-e1730801141567.jpg","type":"image\/jpeg"}],"author":"Comunicaci\u00f3n Vedrunam\u00e9rica","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Comunicaci\u00f3n Vedrunam\u00e9rica","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/#article","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/"},"author":{"name":"Comunicaci\u00f3n Vedrunam\u00e9rica","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/cf468646189533fb6a3aae475663fdc7"},"headline":"\u00ab\u00a0La fragilit\u00e9 de la jeunesse est la force de la transformation sociale\u00a0\u00bb &#8211; Journ\u00e9e nationale de la jeunesse au Br\u00e9sil","datePublished":"2024-11-11T10:05:47+00:00","dateModified":"2024-11-11T10:06:03+00:00","mainEntityOfPage":{"@id":"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/"},"wordCount":372,"publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"image":{"@id":"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/principal-e1730801141567.jpg","articleSection":["Br\u00e9sil","Non classifi\u00e9(e)","Vedrunamerica"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/","url":"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/","name":"\"La fragilit\u00e9 de la jeunesse est la force de la transformation sociale\" - Journ\u00e9e nationale de la jeunesse au Br\u00e9sil - Carmelitas de la Caridad Vedruna","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/#primaryimage"},"image":{"@id":"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/principal-e1730801141567.jpg","datePublished":"2024-11-11T10:05:47+00:00","dateModified":"2024-11-11T10:06:03+00:00","description":"Plus de 350 jeunes de 12 paroisses se sont r\u00e9unis les 26 et 27 octobre pour r\u00e9fl\u00e9chir ensemble sur la foi, la fraternit\u00e9 et l'esp\u00e9rance.","breadcrumb":{"@id":"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/#primaryimage","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/principal-e1730801141567.jpg","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/principal-e1730801141567.jpg","width":1394,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/vedruna.org\/fr\/la-fragilite-de-la-jeunesse-est-la-force-de-la-transformation-sociale-journee-nationale-de-la-jeunesse-au-bresil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vedruna.org\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00a0La fragilit\u00e9 de la jeunesse est la force de la transformation sociale\u00a0\u00bb &#8211; Journ\u00e9e nationale de la jeunesse au Br\u00e9sil"}]},{"@type":"WebSite","@id":"https:\/\/vedruna.org\/fr\/#website","url":"https:\/\/vedruna.org\/fr\/","name":"Carmelitas de la Caridad Vedruna","description":"Carmelitas de la caridad","publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vedruna.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vedruna.org\/fr\/#organization","name":"Carmelitas de la caridad Vedruna","url":"https:\/\/vedruna.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","width":1200,"height":463,"caption":"Carmelitas de la caridad Vedruna"},"image":{"@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/cf468646189533fb6a3aae475663fdc7","name":"Comunicaci\u00f3n Vedrunam\u00e9rica","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g","caption":"Comunicaci\u00f3n Vedrunam\u00e9rica"},"url":"https:\/\/vedruna.org\/fr\/author\/comunicacion-vedrunamerica\/"}]}},"_links":{"self":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/14522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/comments?post=14522"}],"version-history":[{"count":1,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/14522\/revisions"}],"predecessor-version":[{"id":14523,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/14522\/revisions\/14523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media\/14338"}],"wp:attachment":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media?parent=14522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/categories?post=14522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/tags?post=14522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}