{"id":14683,"date":"2024-11-12T14:56:22","date_gmt":"2024-11-12T13:56:22","guid":{"rendered":"https:\/\/vedruna.org\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/"},"modified":"2024-11-12T14:59:55","modified_gmt":"2024-11-12T13:59:55","slug":"chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique","status":"publish","type":"post","link":"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/","title":{"rendered":"Chronique du voyage de l&rsquo;\u00e9quipe g\u00e9n\u00e9rale dans la province d&rsquo;Afrique"},"content":{"rendered":"\n<p>Entre novembre 2024 et janvier 2025, les s\u0153urs <strong>Mar\u00eda Teresa Cuervo et Mar\u00eda Jos\u00e9 Meira (Ded\u00e9 <\/strong>) se rendront, au nom de l&rsquo;\u00e9quipe g\u00e9n\u00e9rale, dans la <strong>province d&rsquo;Afrique. <\/strong> <\/p>\n\n<p>Vous trouverez ci-dessous la chronique de leur voyage, qui sera mise \u00e0 jour p\u00e9riodiquement au fur et \u00e0 mesure qu&rsquo;ils nous enverront des nouvelles.  <\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<h2 class=\"wp-block-heading\"><strong>Premi\u00e8re \u00e9tape : Guin\u00e9e \u00e9quatoriale<\/strong><\/h2>\n\n<p>Notre voyage commence en Guin\u00e9e \u00e9quatoriale, o\u00f9 nous visitons les villes de Bata et d&rsquo;A\u00f1isok.  <\/p>\n\n<p>Le d\u00e9but a \u00e9t\u00e9 mouvement\u00e9, car le 3 novembre, nous avons d\u00fb passer la nuit \u00e0 l&rsquo;h\u00f4tel Villa Brenda \u00e0 Malabo, la capitale insulaire du pays, en raison de probl\u00e8mes m\u00e9caniques de l&rsquo;avion qui devait nous emmener de Malabo \u00e0 Bata. La compagnie a\u00e9rienne nous a transf\u00e9r\u00e9s dans cet h\u00f4tel, tr\u00e8s agr\u00e9able et confortable, avec une vue magnifique sur la mer du golfe de Guin\u00e9e \u00e9quatoriale.   <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14534\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241103_145600583-1024x768.jpg\" alt=\"\" class=\"wp-image-14534\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241103_145600583-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241103_145600583-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"14530\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241103_145320139-768x1024.jpg\" alt=\"\" class=\"wp-image-14530\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14526\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241103_145553398-1024x768.jpg\" alt=\"\" class=\"wp-image-14526\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241103_145553398-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241103_145553398-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h4 class=\"wp-block-heading\">Robe<\/h4>\n\n<p>Le lendemain matin, nous avons pu prendre l&rsquo;avion pour Bata, et par le hublot, nous avons vu les champs tr\u00e8s verts et le volcan de l&rsquo;\u00eele de Malabo. Enfin, nous sommes arriv\u00e9es \u00e0 <strong>notre maison \u00e0 Bata<\/strong>, o\u00f9 nous avons visit\u00e9 la chapelle et rencontr\u00e9 la communaut\u00e9 : nos s\u0153urs <strong>Marie Atumesa Luyinda, Rosette Kazunga Ngemba, Gilberte Kilokila Lumbemba et Adolphine Zunzu Mukala<\/strong> nous attendaient.   <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"14542\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241104_071718762-768x1024.jpg\" alt=\"\" class=\"wp-image-14542\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"864\" height=\"1024\" data-id=\"14562\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241104_082835567-864x1024.jpg\" alt=\"\" class=\"wp-image-14562\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"14548\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241104_074256721_HDR-768x1024.jpg\" alt=\"\" class=\"wp-image-14548\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14554\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241104_172750119-1024x768.jpg\" alt=\"\" class=\"wp-image-14554\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241104_172750119-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241104_172750119-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14546\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241105_1905411392-1024x768.jpg\" alt=\"\" class=\"wp-image-14546\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241105_1905411392-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241105_1905411392-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"632\" data-id=\"14538\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241105_1906373802-1024x632.jpg\" alt=\"\" class=\"wp-image-14538\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241105_1906373802-980x605.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241105_1906373802-480x296.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14558\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241105_0838546612-1024x768.jpg\" alt=\"\" class=\"wp-image-14558\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241105_0838546612-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241105_0838546612-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"761\" data-id=\"14565\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241104_1727410122-1024x761.jpg\" alt=\"\" class=\"wp-image-14565\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241104_1727410122-980x728.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241104_1727410122-480x357.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"14570\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241104_082846724-768x1024.jpg\" alt=\"\" class=\"wp-image-14570\"\/><\/figure>\n<\/figure>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Le 5 novembre, nous avons visit\u00e9 l&rsquo;<strong>\u00e9glise de la paroisse Saint-Fran\u00e7ois-Xavier<\/strong>, o\u00f9 les s\u0153urs m\u00e8nent des activit\u00e9s pastorales, en particulier avec les jeunes et la cat\u00e9ch\u00e8se, et nous avons appris \u00e0 mieux conna\u00eetre la maison de la communaut\u00e9, en visitant des espaces tels que le quintal. Nous avons tenu une autre r\u00e9union avec la communaut\u00e9 et avons termin\u00e9 la journ\u00e9e par une promenade nocturne au bord de la mer.   <\/p>\n\n<p>Le mercredi 6 \u00e9tait notre dernier jour \u00e0 Bata, et nous nous sommes rendus \u00e0 l&rsquo;<strong>\u00e9cole Kisito Vedruna<\/strong>, qui est tr\u00e8s proche de la maison des s\u0153urs, compte 330 \u00e9l\u00e8ves et est subventionn\u00e9e par l&rsquo;Etat. Nous avons remarqu\u00e9 les fresques murales d\u00e9di\u00e9es \u00e0 Sainte Joaquina qui sont peintes sur les murs, et nous avons \u00e9t\u00e9 accueillis par les \u00e9l\u00e8ves qui chantent et dansent, avec beaucoup de joie !   <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14586\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_111118952_HDR-1024x768.jpg\" alt=\"\" class=\"wp-image-14586\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_111118952_HDR-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_111118952_HDR-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14594\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_110603344_HDR-1024x768.jpg\" alt=\"\" class=\"wp-image-14594\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_110603344_HDR-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_110603344_HDR-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14598\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_104907527-1024x768.jpg\" alt=\"\" class=\"wp-image-14598\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_104907527-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_104907527-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"807\" data-id=\"14590\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_103454690-1024x807.jpg\" alt=\"\" class=\"wp-image-14590\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_103454690-980x773.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_103454690-480x378.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14602\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_103508885-1024x768.jpg\" alt=\"\" class=\"wp-image-14602\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_103508885-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_103508885-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>L&rsquo;un des professeurs de l&rsquo;\u00e9cole nous a souhait\u00e9 la bienvenue :  <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab\u00a0Dans la recherche constante de l&rsquo;excellence acad\u00e9mique et humaine, nous tendons \u00e0 offrir une \u00e9ducation int\u00e9grale&#8230; des attitudes sp\u00e9ciales et des valeurs morales qui naissent de la v\u00e9ritable inspiration de notre m\u00e8re, Sainte Joaquina de Vedruna\u00a0\u00bb.<\/em><\/p>\n<\/blockquote>\n\n<p>Nous avons visit\u00e9 tous ses espaces : la salle de direction, le secr\u00e9tariat, les salles de classe, le jardin et les espaces en construction. Nous avons \u00e9t\u00e9 rejointes par l&rsquo;\u00e9quipe provinciale d&rsquo;Afrique : S\u0153urs Marguerite Mbima, Pascaline Kikula et Marguerite Bwandala. <\/p>\n\n<p>Nous terminons notre visite de Bata par une promenade sur le front de mer, en admirant la mer et les b\u00e2timents, comme la tour de Bata.  <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14574\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_174238114_HDR-1024x768.jpg\" alt=\"\" class=\"wp-image-14574\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_174238114_HDR-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_174238114_HDR-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14582\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_174441463-1024x768.jpg\" alt=\"\" class=\"wp-image-14582\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_174441463-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241106_174441463-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h4 class=\"wp-block-heading\">A\u00f1isok<\/h4>\n\n<p>Le lendemain, nous nous sommes rendus \u00e0 A\u00f1isok avec l&rsquo;\u00e9quipe provinciale d&rsquo;Afrique, en parcourant 145 km \u00e0 l&rsquo;int\u00e9rieur des terres, loin de la c\u00f4te. Par la fen\u00eatre, le paysage de la for\u00eat tropicale attire notre attention.   <\/p>\n\n<p>Nous avons \u00e9t\u00e9 accueillis \u00e0 A\u00f1isok par la communaut\u00e9 et avons visit\u00e9 toutes les parties de la maison. Dans l&rsquo;apr\u00e8s-midi, nous avons tenu une r\u00e9union communautaire, un moment pour partager la vie de la communaut\u00e9 en mission. Nous avons \u00e9galement appr\u00e9ci\u00e9 la visite de notre ami <strong>Adum, imam de la communaut\u00e9 islamique d&rsquo;A\u00f1isok<\/strong>, avec laquelle notre communaut\u00e9 et l&rsquo;\u00e9glise locale marchent ensemble dans l&rsquo;entraide et l&rsquo;amiti\u00e9.  <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"662\" height=\"432\" data-id=\"14611\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241107-WA0023.jpg\" alt=\"\" class=\"wp-image-14611\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241107-WA0023.jpg 662w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241107-WA0023-480x313.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 662px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14619\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241107_181143056-1024x768.jpg\" alt=\"\" class=\"wp-image-14619\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241107_181143056-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241107_181143056-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14623\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241107_181111149-1024x768.jpg\" alt=\"\" class=\"wp-image-14623\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241107_181111149-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241107_181111149-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"743\" height=\"557\" data-id=\"14687\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241107-WA0010-edited.jpg\" alt=\"\" class=\"wp-image-14687\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241107-WA0010-edited.jpg 743w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241107-WA0010-edited-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 743px, 100vw\" \/><\/figure>\n<\/figure>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Le 8 novembre, nous sommes parties t\u00f4t pour visiter l&rsquo;<strong> \u00e9glise de la paroisse Saint Pierre Ap\u00f4tre<\/strong>, o\u00f9 les s\u0153urs exercent des activit\u00e9s pastorales : cat\u00e9ch\u00e8se, jeunesse, liturgie et autres. En chemin, nous sommes pass\u00e9s devant le bar \u00ab\u00a0Las hermanas incansables\u00a0\u00bb, situ\u00e9 pr\u00e8s de notre maison, qui a attir\u00e9 notre attention.   <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14631\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_062226004-1024x768.jpg\" alt=\"\" class=\"wp-image-14631\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_062226004-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_062226004-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"14635\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_071330396_HDR-768x1024.jpg\" alt=\"\" class=\"wp-image-14635\"\/><\/figure>\n<\/figure>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Enfin, nous arrivons \u00e0 l&rsquo;<strong>\u00e9cole Vedruna \u00e0 A\u00f1isok <\/strong>. Elle compte 512 \u00e9l\u00e8ves et est subventionn\u00e9e par l&rsquo;Etat. Nous avons visit\u00e9 toute l&rsquo;\u00e9cole : l&rsquo;entr\u00e9e, la cour, le puits, la salle de gestion&#8230; et m\u00eame la salle des f\u00eates, qui est encore en construction. Nous avons \u00e9t\u00e9 frapp\u00e9s par la salle informatique, dont toutes les classes sont \u00e9quip\u00e9es, bien qu&rsquo;elles n&rsquo;aient pas acc\u00e8s \u00e0 Internet, mais les \u00e9l\u00e8ves apprennent \u00e0 utiliser les ordinateurs et leurs diff\u00e9rents programmes.    <\/p>\n\n<p>Dans toute l&rsquo;\u00e9cole, nous avons trouv\u00e9 de nombreuses peintures murales avec des phrases inspirantes. Et nous observons l&rsquo;engagement pris par le groupe d&rsquo;enseignants de l&rsquo;\u00e9cole, dans le cadre d&rsquo;un processus participatif :   <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Respecter et appliquer le r\u00e8glement int\u00e9rieur, travailler en \u00e9quipe, se soutenir mutuellement et \u00e9viter tout ce qui nous emp\u00eache d&rsquo;\u00eatre de bons enseignants.  <\/em><\/p>\n<\/blockquote>\n\n<p>Nous avons travers\u00e9 des classes avec une moyenne de 50 \u00e9l\u00e8ves par classe, et Mariate s&rsquo;est amus\u00e9e \u00e0 enseigner la musique aux enfants, qui ont particip\u00e9 avec enthousiasme. Nous avons \u00e9galement eu la chance d&rsquo;assister \u00e0 un match de football local et de voir comment les \u00e9l\u00e8ves ont c\u00e9l\u00e9br\u00e9 avec joie la fin du match ! <\/p>\n\n<p>Nous avons termin\u00e9 notre visite de l&rsquo;\u00e9cole par une visite de la cour et de la grotte de la Vierge, o\u00f9, pendant le mois de mai, les \u00e9l\u00e8ves passent du temps \u00e0 prier Notre Dame.  <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14639\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_103419289_HDR-1-1024x768.jpg\" alt=\"\" class=\"wp-image-14639\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_103419289_HDR-1-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_103419289_HDR-1-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"14640\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_105519689_HDR-768x1024.jpg\" alt=\"\" class=\"wp-image-14640\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14651\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_110700514-1024x768.jpg\" alt=\"\" class=\"wp-image-14651\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_110700514-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_110700514-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"740\" data-id=\"14659\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_111603531-1024x740.jpg\" alt=\"\" class=\"wp-image-14659\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_111603531-980x709.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_111603531-480x347.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"14647\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_112636486-scaled-e1731414331593.jpg\" alt=\"\" class=\"wp-image-14647\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"14655\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_120355389_HDR-768x1024.jpg\" alt=\"\" class=\"wp-image-14655\"\/><\/figure>\n<\/figure>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Nous nous sommes ensuite rendus au Sanctuaire de la Vierge, \u00e0 c\u00f4t\u00e9 de l&rsquo;\u00e9glise Saint-Pierre-Ap\u00f4tre, o\u00f9 l&rsquo;on c\u00e9l\u00e8bre un samedi par mois la d\u00e9dicace \u00e0 la Vierge. Et nous avons eu la chance de pouvoir \u00e9couter la <strong>chorale des carm\u00e9lites de la paroisse Saint-Pierre-Ap\u00f4tre<\/strong>. Il y a plusieurs chorales dans la paroisse, et chaque jour une chorale diff\u00e9rente prend en charge le chant de la messe.  <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14667\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241109_065951054_HDR-1024x768.jpg\" alt=\"\" class=\"wp-image-14667\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241109_065951054_HDR-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241109_065951054_HDR-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"14663\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241109_070013078_HDR-1024x768.jpg\" alt=\"\" class=\"wp-image-14663\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241109_070013078_HDR-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241109_070013078_HDR-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:34% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241109_102123871-1024x768.jpg\" alt=\"\" class=\"wp-image-14671 size-full\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241109_102123871-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241109_102123871-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>A la fin de la journ\u00e9e, nous avons re\u00e7u la visite de S\u0153ur <strong>Patricia, missionnaire de la Congr\u00e9gation mexicaine des S\u0153urs Dominicaines de la Doctrine Chr\u00e9tienne<\/strong>, qui ont une \u00e9cole \u00e0 Ayene, pr\u00e8s d&rsquo;A\u00f1isok, et qui sont tr\u00e8s amicales avec notre communaut\u00e9. Elle nous a dit combien il est bon de participer ensemble au groupe de Vie Religieuse de la r\u00e9gion, ils font un bon voyage ensemble !  <\/p>\n<\/div><\/div>\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 30%\"><div class=\"wp-block-media-text__content\">\n<p>Le dimanche 10 novembre, nous avons assist\u00e9 \u00e0 la messe \u00e0 l&rsquo;\u00e9glise paroissiale Saint-Pierre d&rsquo;A\u00f1isok, en langue fang, qui pr\u00e9domine dans la ville.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241110-WA0011-1024x768.jpg\" alt=\"\" class=\"wp-image-14675 size-full\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241110-WA0011-1024x768.jpg 1024w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241110-WA0011-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG-20241110-WA0011-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure><\/div>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<p>Pendant toutes ces journ\u00e9es, nous avons rempli l&rsquo;objectif que nous nous \u00e9tions fix\u00e9, \u00e0 savoir aborder la <strong>r\u00e9alit\u00e9 de notre pr\u00e9sence Vedruna en Guin\u00e9e \u00e9quatoriale<\/strong>, avec une attitude d&rsquo;\u00e9coute, d&rsquo;ouverture, de dialogue et de partage de la vie, en ouvrant de nouveaux horizons pour la vie en mission de ces deux pr\u00e9sences dans ce pays.  <\/p>\n\n<p>Nous appr\u00e9cions vraiment l&rsquo;\u00e9change culturel et tout ce que nous apprenons de nos s\u0153urs africaines. Voici quelques-unes des choses qui ont retenu notre attention :   <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Les grands <strong>b\u00e2timents <\/strong>monumentaux, <strong>inachev\u00e9s <\/strong>et abandonn\u00e9s. Ils font partie du paysage des deux villes que nous avons travers\u00e9es.   <\/li>\n\n\n\n<li>Les \u00e9trangers ou les migrants sont souvent appel\u00e9s<strong>\u00ab\u00a0expatri\u00e9s<\/strong>\u00ab\u00a0. Les s\u0153urs nous ont dit qu&rsquo;il \u00e9tait difficile d&rsquo;accueillir des \u00e9trangers. Les s\u0153urs sont les bienvenues, car il existe un accord de coop\u00e9ration nationale entre le gouvernement et l&rsquo;Eglise, et elles peuvent occuper des postes de service.  <\/li>\n\n\n\n<li>Lorsqu&rsquo;ils re\u00e7oivent un visiteur de l&rsquo;ext\u00e9rieur, certains groupes d&rsquo;\u00e9glises font souvent une <strong>collecte d&rsquo;argent<\/strong> pour permettre aux visiteurs d&rsquo;acheter ce qu&rsquo;ils souhaitent manger.<\/li>\n\n\n\n<li><strong>La cuisine locale<\/strong>: nous avons mang\u00e9 de la viande de porc-\u00e9pic, car il est de coutume de manger de la viande d&rsquo;animaux sauvages. Nous avons \u00e9galement go\u00fbt\u00e9 au \u00ab\u00a0Pumpkin wrap\u00a0\u00bb ou \u00ab\u00a0white pumpkin anita\u00a0\u00bb, un plat typique de la tribu Fang, pr\u00e9dominante dans la r\u00e9gion. Et le \u00ab\u00a0fufu\u00a0\u00bb, l&rsquo;aliment de base des habitants de la R\u00e9publique d\u00e9mocratique du Congo (RDC), qui consiste en un m\u00e9lange de ma\u00efs et de farine de manioc &#8211; nous avons m\u00eame pu assister \u00e0 sa pr\u00e9paration par Gilberte !   <\/li>\n\n\n\n<li>Les <strong>coiffures<\/strong> des femmes africaines, en raison de leur complexit\u00e9 et de leur beaut\u00e9.  <\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Entre novembre 2024 et janvier 2025, les s\u0153urs Mar\u00eda Teresa Cuervo et Mar\u00eda Jos\u00e9 Meira (Ded\u00e9 ) se rendront, au nom de l&rsquo;\u00e9quipe g\u00e9n\u00e9rale, dans la province d&rsquo;Afrique. Vous trouverez ci-dessous la chronique de leur voyage, qui sera mise \u00e0 jour p\u00e9riodiquement au fur et \u00e0 mesure qu&rsquo;ils nous enverront des nouvelles. Premi\u00e8re \u00e9tape : [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":14650,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[382,81],"tags":[],"class_list":["post-14683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-equipement-general","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chronique du voyage de l&#039;\u00e9quipe g\u00e9n\u00e9rale dans la province d&#039;Afrique - Carmelitas de la Caridad Vedruna<\/title>\n<meta name=\"description\" content=\"Entre novembre 2024 et janvier 2025, les s\u0153urs Maria Teresa Cuervo et Maria Jos\u00e9 Meira (Ded\u00e9) visiteront les communaut\u00e9s Vedruna en Afrique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chronique du voyage de l&#039;\u00e9quipe g\u00e9n\u00e9rale dans la province d&#039;Afrique - Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"og:description\" content=\"Entre novembre 2024 et janvier 2025, les s\u0153urs Maria Teresa Cuervo et Maria Jos\u00e9 Meira (Ded\u00e9) visiteront les communaut\u00e9s Vedruna en Afrique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/\" \/>\n<meta property=\"og:site_name\" content=\"Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-12T13:56:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-12T13:59:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_112636486-scaled-e1731414331593.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maria Agustina G\u00f3mez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Agustina G\u00f3mez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\\\/\"},\"author\":{\"name\":\"Maria Agustina G\u00f3mez\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/95fe789adf27c2831fc5a049c727edf5\"},\"headline\":\"Chronique du voyage de l&rsquo;\u00e9quipe g\u00e9n\u00e9rale dans la province d&rsquo;Afrique\",\"datePublished\":\"2024-11-12T13:56:22+00:00\",\"dateModified\":\"2024-11-12T13:59:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\\\/\"},\"wordCount\":1408,\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/IMG_20241108_112636486-scaled-e1731510579834.jpg\",\"articleSection\":[\"\u00c9quipe G\u00e9n\u00e9rale\",\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\\\/\",\"name\":\"Chronique du voyage de l'\u00e9quipe g\u00e9n\u00e9rale dans la province d'Afrique - Carmelitas de la Caridad Vedruna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/IMG_20241108_112636486-scaled-e1731510579834.jpg\",\"datePublished\":\"2024-11-12T13:56:22+00:00\",\"dateModified\":\"2024-11-12T13:59:55+00:00\",\"description\":\"Entre novembre 2024 et janvier 2025, les s\u0153urs Maria Teresa Cuervo et Maria Jos\u00e9 Meira (Ded\u00e9) visiteront les communaut\u00e9s Vedruna en Afrique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vedruna.org\\\/fr\\\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/IMG_20241108_112636486-scaled-e1731510579834.jpg\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/IMG_20241108_112636486-scaled-e1731510579834.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chronique du voyage de l&#8217;\u00e9quipe g\u00e9n\u00e9rale dans la province d&#8217;Afrique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"name\":\"Carmelitas de la Caridad Vedruna\",\"description\":\"Carmelitas de la caridad\",\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\",\"name\":\"Carmelitas de la caridad Vedruna\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"width\":1200,\"height\":463,\"caption\":\"Carmelitas de la caridad Vedruna\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/95fe789adf27c2831fc5a049c727edf5\",\"name\":\"Maria Agustina G\u00f3mez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g\",\"caption\":\"Maria Agustina G\u00f3mez\"},\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/author\\\/agustina-gomez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chronique du voyage de l'\u00e9quipe g\u00e9n\u00e9rale dans la province d'Afrique - Carmelitas de la Caridad Vedruna","description":"Entre novembre 2024 et janvier 2025, les s\u0153urs Maria Teresa Cuervo et Maria Jos\u00e9 Meira (Ded\u00e9) visiteront les communaut\u00e9s Vedruna en Afrique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/","og_locale":"fr_FR","og_type":"article","og_title":"Chronique du voyage de l'\u00e9quipe g\u00e9n\u00e9rale dans la province d'Afrique - Carmelitas de la Caridad Vedruna","og_description":"Entre novembre 2024 et janvier 2025, les s\u0153urs Maria Teresa Cuervo et Maria Jos\u00e9 Meira (Ded\u00e9) visiteront les communaut\u00e9s Vedruna en Afrique.","og_url":"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/","og_site_name":"Carmelitas de la Caridad Vedruna","article_published_time":"2024-11-12T13:56:22+00:00","article_modified_time":"2024-11-12T13:59:55+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_112636486-scaled-e1731414331593.jpg","type":"image\/jpeg"}],"author":"Maria Agustina G\u00f3mez","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Maria Agustina G\u00f3mez","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/#article","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/"},"author":{"name":"Maria Agustina G\u00f3mez","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/95fe789adf27c2831fc5a049c727edf5"},"headline":"Chronique du voyage de l&rsquo;\u00e9quipe g\u00e9n\u00e9rale dans la province d&rsquo;Afrique","datePublished":"2024-11-12T13:56:22+00:00","dateModified":"2024-11-12T13:59:55+00:00","mainEntityOfPage":{"@id":"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/"},"wordCount":1408,"publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"image":{"@id":"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_112636486-scaled-e1731510579834.jpg","articleSection":["\u00c9quipe G\u00e9n\u00e9rale","Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/","url":"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/","name":"Chronique du voyage de l'\u00e9quipe g\u00e9n\u00e9rale dans la province d'Afrique - Carmelitas de la Caridad Vedruna","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/#primaryimage"},"image":{"@id":"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_112636486-scaled-e1731510579834.jpg","datePublished":"2024-11-12T13:56:22+00:00","dateModified":"2024-11-12T13:59:55+00:00","description":"Entre novembre 2024 et janvier 2025, les s\u0153urs Maria Teresa Cuervo et Maria Jos\u00e9 Meira (Ded\u00e9) visiteront les communaut\u00e9s Vedruna en Afrique.","breadcrumb":{"@id":"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/#primaryimage","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_112636486-scaled-e1731510579834.jpg","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2024\/11\/IMG_20241108_112636486-scaled-e1731510579834.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/vedruna.org\/fr\/chronique-du-voyage-de-lequipe-generale-dans-la-province-dafrique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vedruna.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Chronique du voyage de l&#8217;\u00e9quipe g\u00e9n\u00e9rale dans la province d&#8217;Afrique"}]},{"@type":"WebSite","@id":"https:\/\/vedruna.org\/fr\/#website","url":"https:\/\/vedruna.org\/fr\/","name":"Carmelitas de la Caridad Vedruna","description":"Carmelitas de la caridad","publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vedruna.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vedruna.org\/fr\/#organization","name":"Carmelitas de la caridad Vedruna","url":"https:\/\/vedruna.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","width":1200,"height":463,"caption":"Carmelitas de la caridad Vedruna"},"image":{"@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/95fe789adf27c2831fc5a049c727edf5","name":"Maria Agustina G\u00f3mez","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g","caption":"Maria Agustina G\u00f3mez"},"url":"https:\/\/vedruna.org\/fr\/author\/agustina-gomez\/"}]}},"_links":{"self":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/14683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/comments?post=14683"}],"version-history":[{"count":2,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/14683\/revisions"}],"predecessor-version":[{"id":14699,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/14683\/revisions\/14699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media\/14650"}],"wp:attachment":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media?parent=14683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/categories?post=14683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/tags?post=14683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}