{"id":21009,"date":"2025-03-01T07:58:00","date_gmt":"2025-03-01T06:58:00","guid":{"rendered":"https:\/\/vedruna.org\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/"},"modified":"2025-03-17T12:59:42","modified_gmt":"2025-03-17T11:59:42","slug":"renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales","status":"publish","type":"post","link":"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/","title":{"rendered":"Renouvellement des v\u0153ux, \u00e0 la mani\u00e8re de Vedruna et en tant que moniales"},"content":{"rendered":"\n<p>En f\u00e9vrier dernier, les 16, 22 et 23 f\u00e9vrier, nous avons renouvel\u00e9 nos v\u0153ux de Carm\u00e9lites de la Charit\u00e9 Vedruna, respectivement Rita, Geral et Loli. Nous sommes toutes les trois conscientes que chaque renouvellement est une occasion sp\u00e9ciale de mettre \u00e0 jour notre d\u00e9vouement et notre engagement au sein de la famille Vedruna. <\/p>\n\n<p>Des chants comme \u00a0\u00bb Fid\u00e8le et uni \u00ab\u00a0, \u00a0\u00bb En toi \u00a0\u00bb ou \u00a0\u00bb Toujours en toi \u00a0\u00bb nous ont particuli\u00e8rement marqu\u00e9s cette ann\u00e9e. De mani\u00e8re diff\u00e9rente, mais avec des mots similaires, nous trois, lors du renouveau, disons \u00e0 nouveau Oui \u00e0 J\u00e9sus, dans l&rsquo;intimit\u00e9 avec Lui, dans le style Vedruna et en tant que religieux. <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Car Dieu veut que mes filles aillent dans de nombreux endroits et elles ne peuvent pas refuser. Dieu b\u00e9nira tout\u00a0\u00bb (Ep. 113).<\/p>\n<\/blockquote>\n\n<p>Nous rendons gr\u00e2ce \u00e0 Dieu pour toutes les personnes qui nous ont accompagn\u00e9s dans la c\u00e9l\u00e9bration, pour nos communaut\u00e9s, pour ceux qui nous encouragent jour apr\u00e8s jour dans la mission et nous rappellent que ce voyage \u00e0 la suite de J\u00e9sus en vaut la peine.<\/p>\n\n<p class=\"has-text-align-right\"><strong>Srs. Rita, Geral et Loli (ccv)<\/strong><\/p>\n<div class=\"pgc-sgb-cb wp-block-pgcsimplygalleryblock-grid \" data-gallery-id=\"a2548173\"><div class=\"sgb-preloader\" id=\"pr_a2548173\">\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div><\/div><div class=\"simply-gallery-amp pgc_sgb_slider \"><noscript><div class=\"sgb-gallery\"><div class=\"sgb-item\"><a href=\"https:\/\/vedruna.org\/?attachment_id=21000\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"240\" loading=\"lazy\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion-300x240.png\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion-300x240.png 300w,https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion-1024x819.png 1024w,https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion.png 2000w\" sizes=\"250px\"\/><\/a><\/div><\/div><\/noscript><\/div><script type=\"application\/json\" class=\"sgb-data\">{\"collectionColumns\":1,\"thumbHieghtRation\":0.7,\"externalLink\":false,\"captions\":false,\"collectionThumbSubMenuDownload\":false,\"collectionThumbSubMenuShare\":false,\"galleryType\":\"pgc_sgb_grid\",\"galleryId\":\"a2548173\",\"images\":[{\"id\":21000,\"title\":\"Collage-renovacion\",\"url\":\"https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion.png\",\"link\":\"https:\/\/vedruna.org\/?attachment_id=21000\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/png\",\"type\":\"image\",\"width\":2000,\"height\":1600,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion-150x150.png\",\"orientation\":\"landscape\"},\"medium\":{\"height\":240,\"width\":300,\"url\":\"https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion-300x240.png\",\"orientation\":\"landscape\"},\"large\":{\"height\":819,\"width\":1024,\"url\":\"https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion-1024x819.png\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion.png\",\"height\":1600,\"width\":2000,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/vedruna.org\/?attachment_id=21000\"}],\"translatedWithWPMLTM\":\"1\",\"itemsMetaDataCollection\":[]}<\/script><script>(function(){if(window.PGC_SGB && window.PGC_SGB.searcher){window.PGC_SGB.searcher.initBlocks()}})()<\/script><\/div>","protected":false},"excerpt":{"rendered":"<p>En f\u00e9vrier dernier, les 16, 22 et 23 f\u00e9vrier, nous avons renouvel\u00e9 nos v\u0153ux de Carm\u00e9lites de la Charit\u00e9 Vedruna, respectivement Rita, Geral et Loli. Nous sommes toutes les trois conscientes que chaque renouvellement est une occasion sp\u00e9ciale de mettre \u00e0 jour notre d\u00e9vouement et notre engagement au sein de la famille Vedruna. Des chants [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":21007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[81,225],"tags":[],"class_list":["post-21009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","category-province-deurope"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Renouvellement des v\u0153ux, \u00e0 la mani\u00e8re de Vedruna et en tant que moniales - Carmelitas de la Caridad Vedruna<\/title>\n<meta name=\"description\" content=\"En f\u00e9vrier dernier, les s\u0153urs Rita, Geral et Loli ont renouvel\u00e9 leurs v\u0153ux en tant que carm\u00e9lites de la Charit\u00e9 de Vedruna.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renouvellement des v\u0153ux, \u00e0 la mani\u00e8re de Vedruna et en tant que moniales - Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"og:description\" content=\"En f\u00e9vrier dernier, les s\u0153urs Rita, Geral et Loli ont renouvel\u00e9 leurs v\u0153ux en tant que carm\u00e9lites de la Charit\u00e9 de Vedruna.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/\" \/>\n<meta property=\"og:site_name\" content=\"Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-01T06:58:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-17T11:59:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"979\" \/>\n\t<meta property=\"og:image:height\" content=\"773\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maria Agustina G\u00f3mez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Agustina G\u00f3mez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\\\/\"},\"author\":{\"name\":\"Maria Agustina G\u00f3mez\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/95fe789adf27c2831fc5a049c727edf5\"},\"headline\":\"Renouvellement des v\u0153ux, \u00e0 la mani\u00e8re de Vedruna et en tant que moniales\",\"datePublished\":\"2025-03-01T06:58:00+00:00\",\"dateModified\":\"2025-03-17T11:59:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\\\/\"},\"wordCount\":203,\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Collage-renovacion-2.png\",\"articleSection\":[\"Non classifi\u00e9(e)\",\"Province d'Europe\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\\\/\",\"name\":\"Renouvellement des v\u0153ux, \u00e0 la mani\u00e8re de Vedruna et en tant que moniales - Carmelitas de la Caridad Vedruna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Collage-renovacion-2.png\",\"datePublished\":\"2025-03-01T06:58:00+00:00\",\"dateModified\":\"2025-03-17T11:59:42+00:00\",\"description\":\"En f\u00e9vrier dernier, les s\u0153urs Rita, Geral et Loli ont renouvel\u00e9 leurs v\u0153ux en tant que carm\u00e9lites de la Charit\u00e9 de Vedruna.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vedruna.org\\\/fr\\\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Collage-renovacion-2.png\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Collage-renovacion-2.png\",\"width\":979,\"height\":773},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renouvellement des v\u0153ux, \u00e0 la mani\u00e8re de Vedruna et en tant que moniales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"name\":\"Carmelitas de la Caridad Vedruna\",\"description\":\"Carmelitas de la caridad\",\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\",\"name\":\"Carmelitas de la caridad Vedruna\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"width\":1200,\"height\":463,\"caption\":\"Carmelitas de la caridad Vedruna\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/95fe789adf27c2831fc5a049c727edf5\",\"name\":\"Maria Agustina G\u00f3mez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g\",\"caption\":\"Maria Agustina G\u00f3mez\"},\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/author\\\/agustina-gomez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renouvellement des v\u0153ux, \u00e0 la mani\u00e8re de Vedruna et en tant que moniales - Carmelitas de la Caridad Vedruna","description":"En f\u00e9vrier dernier, les s\u0153urs Rita, Geral et Loli ont renouvel\u00e9 leurs v\u0153ux en tant que carm\u00e9lites de la Charit\u00e9 de Vedruna.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/","og_locale":"fr_FR","og_type":"article","og_title":"Renouvellement des v\u0153ux, \u00e0 la mani\u00e8re de Vedruna et en tant que moniales - Carmelitas de la Caridad Vedruna","og_description":"En f\u00e9vrier dernier, les s\u0153urs Rita, Geral et Loli ont renouvel\u00e9 leurs v\u0153ux en tant que carm\u00e9lites de la Charit\u00e9 de Vedruna.","og_url":"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/","og_site_name":"Carmelitas de la Caridad Vedruna","article_published_time":"2025-03-01T06:58:00+00:00","article_modified_time":"2025-03-17T11:59:42+00:00","og_image":[{"width":979,"height":773,"url":"https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion-2.png","type":"image\/png"}],"author":"Maria Agustina G\u00f3mez","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Maria Agustina G\u00f3mez","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/#article","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/"},"author":{"name":"Maria Agustina G\u00f3mez","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/95fe789adf27c2831fc5a049c727edf5"},"headline":"Renouvellement des v\u0153ux, \u00e0 la mani\u00e8re de Vedruna et en tant que moniales","datePublished":"2025-03-01T06:58:00+00:00","dateModified":"2025-03-17T11:59:42+00:00","mainEntityOfPage":{"@id":"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/"},"wordCount":203,"publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"image":{"@id":"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion-2.png","articleSection":["Non classifi\u00e9(e)","Province d'Europe"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/","url":"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/","name":"Renouvellement des v\u0153ux, \u00e0 la mani\u00e8re de Vedruna et en tant que moniales - Carmelitas de la Caridad Vedruna","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/#primaryimage"},"image":{"@id":"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion-2.png","datePublished":"2025-03-01T06:58:00+00:00","dateModified":"2025-03-17T11:59:42+00:00","description":"En f\u00e9vrier dernier, les s\u0153urs Rita, Geral et Loli ont renouvel\u00e9 leurs v\u0153ux en tant que carm\u00e9lites de la Charit\u00e9 de Vedruna.","breadcrumb":{"@id":"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/#primaryimage","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion-2.png","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2025\/03\/Collage-renovacion-2.png","width":979,"height":773},{"@type":"BreadcrumbList","@id":"https:\/\/vedruna.org\/fr\/renouvellement-des-voeux-a-la-maniere-de-vedruna-et-en-tant-que-moniales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vedruna.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Renouvellement des v\u0153ux, \u00e0 la mani\u00e8re de Vedruna et en tant que moniales"}]},{"@type":"WebSite","@id":"https:\/\/vedruna.org\/fr\/#website","url":"https:\/\/vedruna.org\/fr\/","name":"Carmelitas de la Caridad Vedruna","description":"Carmelitas de la caridad","publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vedruna.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vedruna.org\/fr\/#organization","name":"Carmelitas de la caridad Vedruna","url":"https:\/\/vedruna.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","width":1200,"height":463,"caption":"Carmelitas de la caridad Vedruna"},"image":{"@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/95fe789adf27c2831fc5a049c727edf5","name":"Maria Agustina G\u00f3mez","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8af3ece86571c098b978434bbc43b948c403c1ae191f09a04e94f916638ceb2c?s=96&d=mm&r=g","caption":"Maria Agustina G\u00f3mez"},"url":"https:\/\/vedruna.org\/fr\/author\/agustina-gomez\/"}]}},"_links":{"self":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/21009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/comments?post=21009"}],"version-history":[{"count":1,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/21009\/revisions"}],"predecessor-version":[{"id":21010,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/21009\/revisions\/21010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media\/21007"}],"wp:attachment":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media?parent=21009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/categories?post=21009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/tags?post=21009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}