{"id":2297,"date":"2023-05-16T14:30:53","date_gmt":"2023-05-16T12:30:53","guid":{"rendered":"https:\/\/vedruna.org\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/"},"modified":"2023-05-17T00:03:30","modified_gmt":"2023-05-16T22:03:30","slug":"explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527","status":"publish","type":"post","link":"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/","title":{"rendered":"Explorer la beaut\u00e9 de l&rsquo;Amazonie p\u00e9ruvienne sur les rives du fleuve Ucayali Quels beaux pieds du messager&#8230; ! Is 52,7"},"content":{"rendered":"\n<p>Ce lundi 15 mai, nous sommes rentr\u00e9s d&rsquo;une visite de quelques villages sur les rives de la rivi\u00e8re Ucayali, situ\u00e9e en Amazonie p\u00e9ruvienne, o\u00f9 se trouve la communaut\u00e9 de Nuevo San Juan.<\/p>\n\n<p>Nous nous sentons des femmes en chemin, vivant chaque jour la nouveaut\u00e9 d&rsquo;un lieu diff\u00e9rent, d&rsquo;une communaut\u00e9 diff\u00e9rente, de personnes diff\u00e9rentes, avec des d\u00e9sirs et des r\u00eaves diff\u00e9rents, cherchant \u00e0 am\u00e9liorer la vie, \u00e0 \u00eatre entendues dans leurs recherches, dans leurs r\u00eaves.<\/p>\n\n<p>Nous avons \u00e9cout\u00e9 le murmure de leurs besoins, les joies de ce qu&rsquo;ils ont accompli, la douleur de leurs absences, les silences des autorit\u00e9s et, en de nombreuses occasions, des agents pastoraux, nous avons touch\u00e9 les cicatrices que la vie a laiss\u00e9es, nous avons \u00e9cout\u00e9 leurs longs silences&#8230; la vie tranquille et parfois bruyante, la vie qui, jour apr\u00e8s jour, se l\u00e8ve \u00e0 l&rsquo;aube, la machette \u00e0 la main, pour parcourir le chemin de la ferme (champ), ou la nuit pour poser les pi\u00e8ges dans la rivi\u00e8re (filets de p\u00eache).<\/p>\n\n<p>Nous avons connu des moments de peur, les difficult\u00e9s de l&rsquo;itin\u00e9rance et de la descente de la rivi\u00e8re dans de petits bateaux, de ne pas savoir o\u00f9 nous passerions la nuit, ce que nous pourrions manger, &#8230; nous avons appr\u00e9ci\u00e9 les petits d\u00e9tails, le partage et la maison simple, mais ouverte \u00e0 notre pr\u00e9sence &#8230; nous avons d\u00e9couvert que les plans que nous avions ne servent pas \u00e0 grand-chose, parce que la vie se d\u00e9veloppe dans le quotidien, dans le petit, dans la proximit\u00e9, dans les choses concr\u00e8tes.<\/p>\n\n<p>Nous d\u00e9couvrons la richesse d\u00e9bordante de la nature, la force de la rivi\u00e8re, la grandeur du ciel \u00e9toil\u00e9, la richesse humaine, la solidarit\u00e9 faite de proximit\u00e9, d&rsquo;accueil et de reconnaissance.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/foto-en-el-texto-1024x576.jpg\" alt=\"\" class=\"wp-image-2257\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/foto-en-el-texto-980x551.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/foto-en-el-texto-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n<p>Nous sommes arriv\u00e9s dans la communaut\u00e9 avec nos sacs \u00e0 dos remplis de visages, d&rsquo;enfants heureux, de sueur et de gratitude, mais aussi de besoins, de rencontres, d&rsquo;espoirs.<\/p>\n\n<p>Notre c\u0153ur n&rsquo;est pas revenu le m\u00eame, il nous dit que nous sommes l\u00e0 o\u00f9 nous devons \u00eatre, que c&rsquo;est l\u00e0 que la vie s&rsquo;entrem\u00eale, que les espoirs se tissent, que l&rsquo;insignifiant prend une force d\u00e9bordante.<\/p>\n\n<p>Nos pieds deviennent agiles et nous voudrions concr\u00e9tiser le texte d&rsquo;Isa\u00efe 52, 7 : <em>Qu&rsquo;ils sont beaux sur les montagnes les pieds du messager qui annonce la paix, qui apporte la bonne nouvelle, qui annonce le salut, qui dit \u00e0 Sion : \u00ab\u00a0Ton Dieu r\u00e8gne d\u00e9j\u00e0 !\u00a0\u00bb<\/em>.<\/p>\n\n<p class=\"has-text-align-center\">Srs. Leonor Valenzuela et Isabel Migu\u00e9lez, CCV<\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2275\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/foto-1024x576.jpg\" alt=\"\" class=\"wp-image-2275\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/foto-980x551.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/foto-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2284\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230411_174013-1024x576.jpg\" alt=\"\" class=\"wp-image-2284\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230411_174013-980x551.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230411_174013-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" data-id=\"2287\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230413_100727-1024x766.jpg\" alt=\"\" class=\"wp-image-2287\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230413_100727-980x733.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230413_100727-480x359.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2260\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230413_173915-1024x576.jpg\" alt=\"\" class=\"wp-image-2260\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230413_173915-980x552.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230413_173915-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2266\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230414_103838-1024x576.jpg\" alt=\"\" class=\"wp-image-2266\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230414_103838-980x551.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230414_103838-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2272\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230505_071609-1024x576.jpg\" alt=\"\" class=\"wp-image-2272\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230505_071609-980x551.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230505_071609-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2263\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230510_171618-1024x576.jpg\" alt=\"\" class=\"wp-image-2263\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230510_171618-980x551.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230510_171618-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2267\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230511_173158-1024x576.jpg\" alt=\"\" class=\"wp-image-2267\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230511_173158-980x551.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230511_173158-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2278\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230512_112759-1024x576.jpg\" alt=\"\" class=\"wp-image-2278\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230512_112759-980x552.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230512_112759-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2290\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/foto-central-2-1024x576.jpg\" alt=\"\" class=\"wp-image-2290\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/foto-central-2-980x551.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/foto-central-2-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ce lundi 15 mai, nous sommes rentr\u00e9s d&rsquo;une visite de quelques villages sur les rives de la rivi\u00e8re Ucayali, situ\u00e9e en Amazonie p\u00e9ruvienne, o\u00f9 se trouve la communaut\u00e9 de Nuevo San Juan. Nous nous sentons des femmes en chemin, vivant chaque jour la nouveaut\u00e9 d&rsquo;un lieu diff\u00e9rent, d&rsquo;une communaut\u00e9 diff\u00e9rente, de personnes diff\u00e9rentes, avec des [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2283,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[155,218,146],"tags":[],"class_list":["post-2297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-perou","category-pucallpa-fr","category-vedrunamerica-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Explorer la beaut\u00e9 de Nuevo San Juan en Amazonie p\u00e9ruvienne<\/title>\n<meta name=\"description\" content=\"Ce lundi 15 mai, nous sommes rentr\u00e9s d&#039;une visite de quelques villages sur les rives de la rivi\u00e8re Ucayali, situ\u00e9e en Amazonie p\u00e9ruvienne, o\u00f9 se trouve la communaut\u00e9 de Nuevo San Juan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Explorer la beaut\u00e9 de Nuevo San Juan en Amazonie p\u00e9ruvienne\" \/>\n<meta property=\"og:description\" content=\"Ce lundi 15 mai, nous sommes rentr\u00e9s d&#039;une visite de quelques villages sur les rives de la rivi\u00e8re Ucayali, situ\u00e9e en Amazonie p\u00e9ruvienne, o\u00f9 se trouve la communaut\u00e9 de Nuevo San Juan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/\" \/>\n<meta property=\"og:site_name\" content=\"Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-16T12:30:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-16T22:03:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230513_072158-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3n Vedrunam\u00e9rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3n Vedrunam\u00e9rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\\\/\"},\"author\":{\"name\":\"Comunicaci\u00f3n Vedrunam\u00e9rica\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/cf468646189533fb6a3aae475663fdc7\"},\"headline\":\"Explorer la beaut\u00e9 de l&rsquo;Amazonie p\u00e9ruvienne sur les rives du fleuve Ucayali Quels beaux pieds du messager&#8230; ! Is 52,7\",\"datePublished\":\"2023-05-16T12:30:53+00:00\",\"dateModified\":\"2023-05-16T22:03:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\\\/\"},\"wordCount\":460,\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/IMG_20230513_072158-scaled.jpg\",\"articleSection\":[\"P\u00e9rou\",\"Pucallpa\",\"Vedrunamerica\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\\\/\",\"name\":\"Explorer la beaut\u00e9 de Nuevo San Juan en Amazonie p\u00e9ruvienne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/IMG_20230513_072158-scaled.jpg\",\"datePublished\":\"2023-05-16T12:30:53+00:00\",\"dateModified\":\"2023-05-16T22:03:30+00:00\",\"description\":\"Ce lundi 15 mai, nous sommes rentr\u00e9s d'une visite de quelques villages sur les rives de la rivi\u00e8re Ucayali, situ\u00e9e en Amazonie p\u00e9ruvienne, o\u00f9 se trouve la communaut\u00e9 de Nuevo San Juan.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vedruna.org\\\/fr\\\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/IMG_20230513_072158-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/IMG_20230513_072158-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Explorer la beaut\u00e9 de l&#8217;Amazonie p\u00e9ruvienne sur les rives du fleuve Ucayali Quels beaux pieds du messager&#8230; ! Is 52,7\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"name\":\"Carmelitas de la Caridad Vedruna\",\"description\":\"Carmelitas de la caridad\",\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\",\"name\":\"Carmelitas de la caridad Vedruna\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"width\":1200,\"height\":463,\"caption\":\"Carmelitas de la caridad Vedruna\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/cf468646189533fb6a3aae475663fdc7\",\"name\":\"Comunicaci\u00f3n Vedrunam\u00e9rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3n Vedrunam\u00e9rica\"},\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/author\\\/comunicacion-vedrunamerica\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Explorer la beaut\u00e9 de Nuevo San Juan en Amazonie p\u00e9ruvienne","description":"Ce lundi 15 mai, nous sommes rentr\u00e9s d'une visite de quelques villages sur les rives de la rivi\u00e8re Ucayali, situ\u00e9e en Amazonie p\u00e9ruvienne, o\u00f9 se trouve la communaut\u00e9 de Nuevo San Juan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/","og_locale":"fr_FR","og_type":"article","og_title":"Explorer la beaut\u00e9 de Nuevo San Juan en Amazonie p\u00e9ruvienne","og_description":"Ce lundi 15 mai, nous sommes rentr\u00e9s d'une visite de quelques villages sur les rives de la rivi\u00e8re Ucayali, situ\u00e9e en Amazonie p\u00e9ruvienne, o\u00f9 se trouve la communaut\u00e9 de Nuevo San Juan.","og_url":"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/","og_site_name":"Carmelitas de la Caridad Vedruna","article_published_time":"2023-05-16T12:30:53+00:00","article_modified_time":"2023-05-16T22:03:30+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230513_072158-scaled.jpg","type":"image\/jpeg"}],"author":"Comunicaci\u00f3n Vedrunam\u00e9rica","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Comunicaci\u00f3n Vedrunam\u00e9rica","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/#article","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/"},"author":{"name":"Comunicaci\u00f3n Vedrunam\u00e9rica","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/cf468646189533fb6a3aae475663fdc7"},"headline":"Explorer la beaut\u00e9 de l&rsquo;Amazonie p\u00e9ruvienne sur les rives du fleuve Ucayali Quels beaux pieds du messager&#8230; ! Is 52,7","datePublished":"2023-05-16T12:30:53+00:00","dateModified":"2023-05-16T22:03:30+00:00","mainEntityOfPage":{"@id":"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/"},"wordCount":460,"publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"image":{"@id":"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230513_072158-scaled.jpg","articleSection":["P\u00e9rou","Pucallpa","Vedrunamerica"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/","url":"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/","name":"Explorer la beaut\u00e9 de Nuevo San Juan en Amazonie p\u00e9ruvienne","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/#primaryimage"},"image":{"@id":"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230513_072158-scaled.jpg","datePublished":"2023-05-16T12:30:53+00:00","dateModified":"2023-05-16T22:03:30+00:00","description":"Ce lundi 15 mai, nous sommes rentr\u00e9s d'une visite de quelques villages sur les rives de la rivi\u00e8re Ucayali, situ\u00e9e en Amazonie p\u00e9ruvienne, o\u00f9 se trouve la communaut\u00e9 de Nuevo San Juan.","breadcrumb":{"@id":"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/#primaryimage","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230513_072158-scaled.jpg","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/05\/IMG_20230513_072158-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/vedruna.org\/fr\/explorer-la-beaute-de-nuevo-san-juan-en-amazonie-peruvienne-quels-beaux-pieds-du-messager-is-527\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vedruna.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Explorer la beaut\u00e9 de l&#8217;Amazonie p\u00e9ruvienne sur les rives du fleuve Ucayali Quels beaux pieds du messager&#8230; ! Is 52,7"}]},{"@type":"WebSite","@id":"https:\/\/vedruna.org\/fr\/#website","url":"https:\/\/vedruna.org\/fr\/","name":"Carmelitas de la Caridad Vedruna","description":"Carmelitas de la caridad","publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vedruna.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vedruna.org\/fr\/#organization","name":"Carmelitas de la caridad Vedruna","url":"https:\/\/vedruna.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","width":1200,"height":463,"caption":"Carmelitas de la caridad Vedruna"},"image":{"@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/cf468646189533fb6a3aae475663fdc7","name":"Comunicaci\u00f3n Vedrunam\u00e9rica","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4eff91ff87ece2131a5d31270e1df0a7eeaffece756ce6503fd7dce879d1bfc?s=96&d=mm&r=g","caption":"Comunicaci\u00f3n Vedrunam\u00e9rica"},"url":"https:\/\/vedruna.org\/fr\/author\/comunicacion-vedrunamerica\/"}]}},"_links":{"self":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/2297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/comments?post=2297"}],"version-history":[{"count":5,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/2297\/revisions"}],"predecessor-version":[{"id":2310,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/2297\/revisions\/2310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media\/2283"}],"wp:attachment":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media?parent=2297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/categories?post=2297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/tags?post=2297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}