{"id":6747,"date":"2023-12-03T20:53:53","date_gmt":"2023-12-03T19:53:53","guid":{"rendered":"https:\/\/vedruna.org\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/"},"modified":"2023-12-04T07:19:17","modified_gmt":"2023-12-04T06:19:17","slug":"cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote","status":"publish","type":"post","link":"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/","title":{"rendered":"COP28 : Unanima &#8211; r\u00e9pondre \u00e0 l&rsquo;urgence de la crise climatique sans \u00ab\u00a0laisser personne de c\u00f4t\u00e9\u00a0\u00bb."},"content":{"rendered":"\n<p><strong>Unanima participe mardi \u00e0 Duba\u00ef \u00e0 un \u00e9v\u00e9nement parall\u00e8le \u00e0 la COP28, qui sera retransmis sur YouTube.<\/strong><\/p>\n\n<p><\/p>\n\n<p><a href=\"https:\/\/unanima-international.org\/\">Unanima International <\/a>participe ce mardi 5 d\u00e9cembre \u00e0 un \u00e9v\u00e9nement parall\u00e8le au Sommet de Duba\u00ef sur le climat, au cours duquel des repr\u00e9sentants d&rsquo;organisations catholiques pr\u00e9senteront la \u00ab\u00a0Charte catholique mondiale sur le changement climatique \u00e0 la pr\u00e9sidence de la COP28\u00a0\u00bb.<\/p>\n\n<p>Elle appelle \u00e0 \u00ab\u00a0acc\u00e9l\u00e9rer la transition vers les \u00e9nergies propres\u00a0\u00bb et \u00e0 faire en sorte que cette transition soit \u00ab\u00a0juste\u00a0\u00bb. Fort de l&rsquo;exp\u00e9rience accumul\u00e9e lors des pr\u00e9c\u00e9dents sommets, il appelle \u00e9galement au s\u00e9rieux dans le respect des engagements pris, en particulier ceux li\u00e9s \u00e0 la facilitation \u00e9conomique des pays du Sud pour qu&rsquo;ils puissent affronter ce processus dans des conditions ad\u00e9quates. Des milliards de dollars d&rsquo;aide ont \u00e9t\u00e9 convenus lors de r\u00e9unions r\u00e9centes pour contribuer \u00e0 la r\u00e9alisation de ces objectifs, mais les promesses sont loin d&rsquo;\u00eatre tenues.<\/p>\n\n<p>L&rsquo;\u00e9v\u00e9nement de mardi sera retransmis de 18h30 \u00e0 20h00 (heure locale ; 15h30-17h00 heure de Rome) sur <a href=\"https:\/\/www.youtube.com\/watch?v=8niyR4YHdTQ\">les cha\u00eenes YouTube du Mouvement Laudato Si<\/a> ou sur la <a href=\"https:\/\/www.youtube.com\/watch?v=ehlOKd8aeuA\">cha\u00eene du sommet de l&rsquo;ONU<\/a>.<\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"The Global Catholic Letter on Climate Change to the COP28 Presidency\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/8niyR4YHdTQ?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<p>Parmi les intervenants figurent Jean Quinn, directeur ex\u00e9cutif d&rsquo;Unanima, et <em>Liana Almony<\/em>, repr\u00e9sentante de l&rsquo;organisation aupr\u00e8s des Nations unies.<\/p>\n\n<p><em>Vedruna est l&rsquo;une des 25 entit\u00e9s religieuses qui font partie de cette coalition qui, depuis 20 ans, m\u00e8ne des activit\u00e9s de plaidoyer au niveau mondial dans les domaines du changement climatique, de l&rsquo;\u00e9galit\u00e9 des sexes et des d\u00e9placements forc\u00e9s.<\/em><\/p>\n\n<div class=\"wp-block-cover\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" class=\"wp-block-cover__image-background wp-image-6734\" alt=\"Jean Quinn, directora ejecutiva de Unanima (derecha), en la COP27 de El Cairo, junto a t Lara Hicks, representante de la entidad en esa cumbre.\" src=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/12\/COP27.jpg\" style=\"object-position:67% 7%\" data-object-fit=\"cover\" data-object-position=\"67% 7%\" srcset=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/12\/COP27.jpg 1000w, https:\/\/vedruna.org\/wp-content\/uploads\/2023\/12\/COP27-980x735.jpg 980w, https:\/\/vedruna.org\/wp-content\/uploads\/2023\/12\/COP27-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size\"><\/p>\n<\/div><\/div>\n\n<p><sub>Jean Quinn, directrice ex\u00e9cutive d&rsquo;Unanima (\u00e0 droite), \u00e0 la COP27 au Caire, en compagnie de Lara Hicks, repr\u00e9sentante de l&rsquo;organisation au sommet.<\/sub><\/p>\n\n<p><\/p>\n\n<p><em>Au sommet de Duba\u00ef, elle participe avec d&rsquo;autres organisations catholiques, r\u00e9it\u00e9rant l&rsquo;urgence de respecter les engagements pris lors des sommets pr\u00e9c\u00e9dents. Dans Laudate Deum, l&rsquo;exhortation qui actualise l&rsquo;encyclique Laudato si, le pape parle d&rsquo;un \u00ab\u00a0point de non-retour\u00a0\u00bb vers lequel, selon de multiples \u00e9tudes, la plan\u00e8te se dirige si des changements drastiques et imm\u00e9diats ne sont pas apport\u00e9s au mod\u00e8le \u00e9conomique.<\/em><\/p>\n\n<p><em>Plut\u00f4t que de se mettre d&rsquo;accord sur de nouveaux objectifs, Unanima pr\u00e9conise un programme clair et coh\u00e9rent d&rsquo;engagements concrets de la part des \u00c9tats lors de ce sommet. Ce \u00ab\u00a0besoin de transformation profonde\u00a0\u00bb des soci\u00e9t\u00e9s explique, selon l&rsquo;Unamina, l&rsquo;importance de l&rsquo;engagement des communaut\u00e9s religieuses en faveur d&rsquo;une r\u00e9ponse ad\u00e9quate \u00e0 la crise climatique bas\u00e9e sur la justice sociale.<\/em><\/p>\n\n<p><em>En particulier, <a href=\"https:\/\/unanima-international.org\/\">l&rsquo;Unamine <\/a>rappelle qu&rsquo;il existe de nombreuses preuves de l&rsquo;impact relativement plus important de la crise climatique sur les femmes, les jeunes filles, les personnes \u00e2g\u00e9es ou les pays pauvres. Cela, en plus d&rsquo;une forte focalisation sur le genre, appelle \u00e9galement \u00e0 un effort renouvel\u00e9 pour r\u00e9aliser l&rsquo;engagement de l&rsquo;Agenda 2030 de \u00ab\u00a0ne laisser personne de c\u00f4t\u00e9\u00a0\u00bb.<\/em><\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unanima participe mardi \u00e0 Duba\u00ef \u00e0 un \u00e9v\u00e9nement parall\u00e8le \u00e0 la COP28, qui sera retransmis sur YouTube. Unanima International participe ce mardi 5 d\u00e9cembre \u00e0 un \u00e9v\u00e9nement parall\u00e8le au Sommet de Duba\u00ef sur le climat, au cours duquel des repr\u00e9sentants d&rsquo;organisations catholiques pr\u00e9senteront la \u00ab\u00a0Charte catholique mondiale sur le changement climatique \u00e0 la pr\u00e9sidence de [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":6725,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[81,319],"tags":[],"class_list":["post-6747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","category-unanima-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COP28 : Unanima - r\u00e9pondre \u00e0 l&#039;urgence de la crise climatique sans &quot;laisser personne de c\u00f4t\u00e9&quot;. - Carmelitas de la Caridad Vedruna<\/title>\n<meta name=\"description\" content=\"Unanima participe \u00e0 la COP28 \u00e0 Duba\u00ef et est l&#039;une des organisations promotrices de la &quot;Charte catholique mondiale sur le changement climatique \u00e0 la pr\u00e9sidence de la COP28&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COP28 : Unanima - r\u00e9pondre \u00e0 l&#039;urgence de la crise climatique sans &quot;laisser personne de c\u00f4t\u00e9&quot;. - Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"og:description\" content=\"Unanima participe \u00e0 la COP28 \u00e0 Duba\u00ef et est l&#039;une des organisations promotrices de la &quot;Charte catholique mondiale sur le changement climatique \u00e0 la pr\u00e9sidence de la COP28&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/\" \/>\n<meta property=\"og:site_name\" content=\"Carmelitas de la Caridad Vedruna\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-03T19:53:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-04T06:19:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/12\/COP-e1701550371984.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Benjumea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Benjumea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\\\/\"},\"author\":{\"name\":\"Ricardo Benjumea\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/ce27b3a623ee7463451959870b4e509f\"},\"headline\":\"COP28 : Unanima &#8211; r\u00e9pondre \u00e0 l&rsquo;urgence de la crise climatique sans \u00ab\u00a0laisser personne de c\u00f4t\u00e9\u00a0\u00bb.\",\"datePublished\":\"2023-12-03T19:53:53+00:00\",\"dateModified\":\"2023-12-04T06:19:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\\\/\"},\"wordCount\":524,\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/COP-e1701550371984.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\",\"Unanima\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\\\/\",\"name\":\"COP28 : Unanima - r\u00e9pondre \u00e0 l'urgence de la crise climatique sans \\\"laisser personne de c\u00f4t\u00e9\\\". - Carmelitas de la Caridad Vedruna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/COP-e1701550371984.jpg\",\"datePublished\":\"2023-12-03T19:53:53+00:00\",\"dateModified\":\"2023-12-04T06:19:17+00:00\",\"description\":\"Unanima participe \u00e0 la COP28 \u00e0 Duba\u00ef et est l'une des organisations promotrices de la \\\"Charte catholique mondiale sur le changement climatique \u00e0 la pr\u00e9sidence de la COP28\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vedruna.org\\\/fr\\\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/COP-e1701550371984.jpg\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/COP-e1701550371984.jpg\",\"width\":1000,\"height\":667,\"caption\":\"At the venue for the COP27 climate summit on Nov. 16 in Sharm el-Sheikh, Egypt (Flickr\\\/UNclimatechange) At the venue for the COP27 climate summit on Nov. 16 in Sharm el-Sheikh, Egypt (Flickr\\\/UNclimatechange)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COP28 : Unanima &#8211; r\u00e9pondre \u00e0 l&#8217;urgence de la crise climatique sans \u00ablaisser personne de c\u00f4t\u00e9\u00bb.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"name\":\"Carmelitas de la Caridad Vedruna\",\"description\":\"Carmelitas de la caridad\",\"publisher\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#organization\",\"name\":\"Carmelitas de la caridad Vedruna\",\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"contentUrl\":\"https:\\\/\\\/vedruna.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/LOGO-VEDRUNA-HORIZONTAL.png\",\"width\":1200,\"height\":463,\"caption\":\"Carmelitas de la caridad Vedruna\"},\"image\":{\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/#\\\/schema\\\/person\\\/ce27b3a623ee7463451959870b4e509f\",\"name\":\"Ricardo Benjumea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd52dd207ade52a2d22a331a6f9f53237aee43eb267161478cf9c5d6a5c87def?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd52dd207ade52a2d22a331a6f9f53237aee43eb267161478cf9c5d6a5c87def?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd52dd207ade52a2d22a331a6f9f53237aee43eb267161478cf9c5d6a5c87def?s=96&d=mm&r=g\",\"caption\":\"Ricardo Benjumea\"},\"url\":\"https:\\\/\\\/vedruna.org\\\/fr\\\/author\\\/ricardo-benjumea\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COP28 : Unanima - r\u00e9pondre \u00e0 l'urgence de la crise climatique sans \"laisser personne de c\u00f4t\u00e9\". - Carmelitas de la Caridad Vedruna","description":"Unanima participe \u00e0 la COP28 \u00e0 Duba\u00ef et est l'une des organisations promotrices de la \"Charte catholique mondiale sur le changement climatique \u00e0 la pr\u00e9sidence de la COP28\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/","og_locale":"fr_FR","og_type":"article","og_title":"COP28 : Unanima - r\u00e9pondre \u00e0 l'urgence de la crise climatique sans \"laisser personne de c\u00f4t\u00e9\". - Carmelitas de la Caridad Vedruna","og_description":"Unanima participe \u00e0 la COP28 \u00e0 Duba\u00ef et est l'une des organisations promotrices de la \"Charte catholique mondiale sur le changement climatique \u00e0 la pr\u00e9sidence de la COP28\".","og_url":"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/","og_site_name":"Carmelitas de la Caridad Vedruna","article_published_time":"2023-12-03T19:53:53+00:00","article_modified_time":"2023-12-04T06:19:17+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/12\/COP-e1701550371984.jpg","type":"image\/jpeg"}],"author":"Ricardo Benjumea","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ricardo Benjumea","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/#article","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/"},"author":{"name":"Ricardo Benjumea","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/ce27b3a623ee7463451959870b4e509f"},"headline":"COP28 : Unanima &#8211; r\u00e9pondre \u00e0 l&rsquo;urgence de la crise climatique sans \u00ab\u00a0laisser personne de c\u00f4t\u00e9\u00a0\u00bb.","datePublished":"2023-12-03T19:53:53+00:00","dateModified":"2023-12-04T06:19:17+00:00","mainEntityOfPage":{"@id":"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/"},"wordCount":524,"publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"image":{"@id":"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/12\/COP-e1701550371984.jpg","articleSection":["Non classifi\u00e9(e)","Unanima"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/","url":"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/","name":"COP28 : Unanima - r\u00e9pondre \u00e0 l'urgence de la crise climatique sans \"laisser personne de c\u00f4t\u00e9\". - Carmelitas de la Caridad Vedruna","isPartOf":{"@id":"https:\/\/vedruna.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/#primaryimage"},"image":{"@id":"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/#primaryimage"},"thumbnailUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/12\/COP-e1701550371984.jpg","datePublished":"2023-12-03T19:53:53+00:00","dateModified":"2023-12-04T06:19:17+00:00","description":"Unanima participe \u00e0 la COP28 \u00e0 Duba\u00ef et est l'une des organisations promotrices de la \"Charte catholique mondiale sur le changement climatique \u00e0 la pr\u00e9sidence de la COP28\".","breadcrumb":{"@id":"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/#primaryimage","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/12\/COP-e1701550371984.jpg","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2023\/12\/COP-e1701550371984.jpg","width":1000,"height":667,"caption":"At the venue for the COP27 climate summit on Nov. 16 in Sharm el-Sheikh, Egypt (Flickr\/UNclimatechange) At the venue for the COP27 climate summit on Nov. 16 in Sharm el-Sheikh, Egypt (Flickr\/UNclimatechange)"},{"@type":"BreadcrumbList","@id":"https:\/\/vedruna.org\/fr\/cop28-unanima-repondre-a-lurgence-de-la-crise-climatique-sans-laisser-personne-de-cote\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vedruna.org\/fr\/"},{"@type":"ListItem","position":2,"name":"COP28 : Unanima &#8211; r\u00e9pondre \u00e0 l&#8217;urgence de la crise climatique sans \u00ablaisser personne de c\u00f4t\u00e9\u00bb."}]},{"@type":"WebSite","@id":"https:\/\/vedruna.org\/fr\/#website","url":"https:\/\/vedruna.org\/fr\/","name":"Carmelitas de la Caridad Vedruna","description":"Carmelitas de la caridad","publisher":{"@id":"https:\/\/vedruna.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vedruna.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vedruna.org\/fr\/#organization","name":"Carmelitas de la caridad Vedruna","url":"https:\/\/vedruna.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","contentUrl":"https:\/\/vedruna.org\/wp-content\/uploads\/2022\/04\/LOGO-VEDRUNA-HORIZONTAL.png","width":1200,"height":463,"caption":"Carmelitas de la caridad Vedruna"},"image":{"@id":"https:\/\/vedruna.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/vedruna.org\/fr\/#\/schema\/person\/ce27b3a623ee7463451959870b4e509f","name":"Ricardo Benjumea","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fd52dd207ade52a2d22a331a6f9f53237aee43eb267161478cf9c5d6a5c87def?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fd52dd207ade52a2d22a331a6f9f53237aee43eb267161478cf9c5d6a5c87def?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd52dd207ade52a2d22a331a6f9f53237aee43eb267161478cf9c5d6a5c87def?s=96&d=mm&r=g","caption":"Ricardo Benjumea"},"url":"https:\/\/vedruna.org\/fr\/author\/ricardo-benjumea\/"}]}},"_links":{"self":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/6747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/comments?post=6747"}],"version-history":[{"count":1,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/6747\/revisions"}],"predecessor-version":[{"id":6749,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/posts\/6747\/revisions\/6749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media\/6725"}],"wp:attachment":[{"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/media?parent=6747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/categories?post=6747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vedruna.org\/fr\/wp-json\/wp\/v2\/tags?post=6747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}